{"id":90905,"date":"2025-09-15T07:02:46","date_gmt":"2025-09-15T05:02:46","guid":{"rendered":"https:\/\/felgenforum.shop\/?post_type=product&#038;p=90905"},"modified":"2026-04-25T15:13:40","modified_gmt":"2026-04-25T13:13:40","slug":"19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e","status":"publish","type":"product","link":"https:\/\/felgenforum.shop\/en\/product\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e\/","title":{"rendered":"19-inch Keskin KT15 polished rims for Mercedes GLA CAE"},"content":{"rendered":"<h3>Welcome to an offer from Felgenforum.shop<\/h3>\n<p>In this offer we offer you a NEW set of Keskin KT15 alloy wheels in black with polished front, including ABE (German type approval).<\/p>\n<p>NEW &amp; in original packaging.<\/p>\n<h3>Scope of delivery:<\/h3>\n<ul>\n<li>4 x Keskin KT15 8,5&#215;19 ET45 5&#215;112\u00a0schwarz frontpoliert<\/li>\n<li>Complete mounting hardware (if required according to the ABE)<\/li>\n<li>4x Keskin hubcaps<\/li>\n<li>(Vehicle manufacturer&#039;s hubcap not included)<\/li>\n<li>1x Expert report (ABE)<\/li>\n<li>In most cases, the rims are therefore registration-free. If you have any questions about fitment or any registration requirements, our experienced team will be happy to help :).<\/li>\n<li>Please be sure to specify your vehicle after purchase.<\/li>\n<li>We offer this model in many other sizes and colors; please contact us if you have any other requests.<\/li>\n<\/ul>\n<h3>&gt;&gt;&gt;Complete wheels<\/h3>\n<h3>We are happy to offer you the desired rims as ready-to-install complete wheels with a tire of your choice.<\/h3>\n<p>Feel free to send us a non-binding inquiry :).<\/p>\n<p>The rims are the correct size for the following vehicles:<\/p>\n<h3>Audi<\/h3>\n<ul>\n<li>A3 S3 8P 8P1 8V GY\u00a0<\/li>\n<li>A4 S4 B8 B81<\/li>\n<li>A6 S6 4F 4F1 C6 4G 4G1 C7 F2 C8<\/li>\n<li>A8 4E<\/li>\n<li>TT TTS TTRS 8J 8S FV<\/li>\n<li>Q2 SQ2 GA<\/li>\n<li>Q3 8U 8U1<\/li>\n<\/ul>\n<h3>Volkswagen<\/h3>\n<ul>\n<li>Beetle 2<\/li>\n<li>EOS<\/li>\n<li>Golf 5 6 7 8 in all versions<\/li>\n<li>ID.3<\/li>\n<li>ID.4<\/li>\n<li>Jetta 1KM 16 16H<\/li>\n<li>Passat B6 B7 B8<\/li>\n<li>Phaeton 3D<\/li>\n<li>Tiguan 5N1<\/li>\n<li>Touran 1T<\/li>\n<li>T-ROC A1<\/li>\n<\/ul>\n<h3>Mercedes Benz<\/h3>\n<ul>\n<li>A-Class W169 W176 W177<\/li>\n<li>B Class W245 W246 W247<\/li>\n<li>C-Class W204 W205 all body styles<\/li>\n<li>CLA Class C117 C118<\/li>\n<li>E-Class W212 W213 all body styles<\/li>\n<li>CL Class C215<\/li>\n<li>EQA250 F2B<\/li>\n<li>GLA 245G F2B<\/li>\n<li>GLB F2B<\/li>\n<li>GLK X204<\/li>\n<li>S-Class W220<\/li>\n<li>Seat<\/li>\n<li>Ateca 5FP also Cupra<\/li>\n<li>Leon 1P 5F KL also Cupra<\/li>\n<li>Karoq NU<\/li>\n<\/ul>\n<h3>Skoda<\/h3>\n<ul>\n<li>Octavia 1Z 5E NX<\/li>\n<li>Superb 2 3 4 3T<\/li>\n<li>Yeti 5L<\/li>\n<\/ul>\n<h3>BMW<\/h3>\n<ul>\n<li>1 Series F40<\/li>\n<li>2 Series F44 F45 F46<\/li>\n<li>X1 F48<\/li>\n<li>X2 F39<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Ein Satz (4 St\u00fcck) hochwertige Marken-Alufelgen, Modell kt15, in der Gr\u00f6\u00dfe 8,5&#215;19 Zoll, Lochkreis 112 mit 5 Loch. Professionell gepr\u00fcft und versandfertig verpackt.<\/p>","protected":false},"featured_media":100901,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1180,1086,1179],"product_tag":[],"class_list":{"0":"post-90905","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-19-zoll","7":"product_cat-felgen","8":"product_cat-mercedes","9":"product_shipping_class-felge","10":"pa_anzahl-der-einheiten-1484","11":"pa_einpresstiefe-et-1508","12":"pa_fahrzeugmarke-mercedes","13":"pa_farbe-schwarz","14":"pa_felgenbreite-8-5","15":"pa_felgendesign-multi-speichen-felge","16":"pa_felgenfarbe-schwarz","17":"pa_felgenmaterial-aluminium","18":"pa_felgenmodell-kt15","19":"pa_hersteller-keskin","20":"pa_herstellergarantie-ja-zwei-jahre","21":"pa_herstellernummer-kt158519511245bfp","22":"pa_herstellungsland-und-regi-deutschland","23":"pa_lochkreis-1439","24":"pa_lochzahl-1447","25":"pa_maximale-traglast-2037","26":"pa_mit-deckel-ja-nein-ja-von-damina","27":"pa_modell-kt15","28":"pa_produktart-kreuzspeiche","29":"pa_zollgroesse-1448","31":"first","32":"instock","33":"taxable","34":"shipping-taxable","35":"purchasable","36":"product-type-simple"},"yoast_head":"<title>19 Zoll Felgen Keskin KT15 poliert f\u00fcr Mercedes GLA C A E g\u00fcnstig kaufen - Felgenforum<\/title>\n<meta name=\"description\" content=\"Verleihen Sie Ihrem Mercedes mit Keskin KT15 19 Zoll Felgen in polierter Optik ein sportliches Design. Perfekte Passform und edler Look. Jetzt entdecken!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/felgenforum.shop\/en\/product\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"19 Zoll Felgen Keskin KT15 poliert f\u00fcr Mercedes GLA C A E g\u00fcnstig kaufen - Felgenforum\" \/>\n<meta property=\"og:description\" content=\"Verleihen Sie Ihrem Mercedes mit Keskin KT15 19 Zoll Felgen in polierter Optik ein sportliches Design. Perfekte Passform und edler Look. Jetzt entdecken!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/felgenforum.shop\/en\/product\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e\/\" \/>\n<meta property=\"og:site_name\" content=\"Felgenforum\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-25T13:13:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e-featured-1000px.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e\\\/\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e\\\/\",\"name\":\"19 Zoll Felgen Keskin KT15 poliert f\u00fcr Mercedes GLA C A E g\u00fcnstig kaufen - Felgenforum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e-featured-1000px.webp\",\"datePublished\":\"2025-09-15T05:02:46+00:00\",\"dateModified\":\"2026-04-25T13:13:40+00:00\",\"description\":\"Verleihen Sie Ihrem Mercedes mit Keskin KT15 19 Zoll Felgen in polierter Optik ein sportliches Design. Perfekte Passform und edler Look. Jetzt entdecken!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e\\\/#primaryimage\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e-featured-1000px.webp\",\"contentUrl\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e-featured-1000px.webp\",\"width\":1000,\"height\":1000,\"caption\":\"Hochwertige 19 Zoll Felgen Keskin KT15 poliert f\u00fcr Mercedes Modelle\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/felgenforum.shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/felgenforum.shop\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"19 Zoll Felgen Keskin KT15 poliert f\u00fcr Mercedes GLA C A E\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/#website\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/\",\"name\":\"Felgenforum\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/felgenforum.shop\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>","yoast_head_json":{"title":"19 Zoll Felgen Keskin KT15 poliert f\u00fcr Mercedes GLA C A E g\u00fcnstig kaufen - Felgenforum","description":"Verleihen Sie Ihrem Mercedes mit Keskin KT15 19 Zoll Felgen in polierter Optik ein sportliches Design. Perfekte Passform und edler Look. Jetzt entdecken!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/felgenforum.shop\/en\/product\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e\/","og_locale":"en_GB","og_type":"article","og_title":"19 Zoll Felgen Keskin KT15 poliert f\u00fcr Mercedes GLA C A E g\u00fcnstig kaufen - Felgenforum","og_description":"Verleihen Sie Ihrem Mercedes mit Keskin KT15 19 Zoll Felgen in polierter Optik ein sportliches Design. Perfekte Passform und edler Look. Jetzt entdecken!","og_url":"https:\/\/felgenforum.shop\/en\/product\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e\/","og_site_name":"Felgenforum","article_modified_time":"2026-04-25T13:13:40+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e-featured-1000px.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e\/","url":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e\/","name":"19 Zoll Felgen Keskin KT15 poliert f\u00fcr Mercedes GLA C A E g\u00fcnstig kaufen - Felgenforum","isPartOf":{"@id":"https:\/\/felgenforum.shop\/#website"},"primaryImageOfPage":{"@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e\/#primaryimage"},"image":{"@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e\/#primaryimage"},"thumbnailUrl":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e-featured-1000px.webp","datePublished":"2025-09-15T05:02:46+00:00","dateModified":"2026-04-25T13:13:40+00:00","description":"Verleihen Sie Ihrem Mercedes mit Keskin KT15 19 Zoll Felgen in polierter Optik ein sportliches Design. Perfekte Passform und edler Look. Jetzt entdecken!","breadcrumb":{"@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e\/#primaryimage","url":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e-featured-1000px.webp","contentUrl":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e-featured-1000px.webp","width":1000,"height":1000,"caption":"Hochwertige 19 Zoll Felgen Keskin KT15 poliert f\u00fcr Mercedes Modelle"},{"@type":"BreadcrumbList","@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-keskin-kt15-poliert-fuer-mercedes-gla-c-a-e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/felgenforum.shop\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/felgenforum.shop\/shop\/"},{"@type":"ListItem","position":3,"name":"19 Zoll Felgen Keskin KT15 poliert f\u00fcr Mercedes GLA C A E"}]},{"@type":"WebSite","@id":"https:\/\/felgenforum.shop\/#website","url":"https:\/\/felgenforum.shop\/","name":"Rim forum","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/felgenforum.shop\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product\/90905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/comments?post=90905"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/media\/100901"}],"wp:attachment":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/media?parent=90905"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_brand?post=90905"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_cat?post=90905"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_tag?post=90905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}