{"id":87603,"date":"2025-09-14T13:56:44","date_gmt":"2025-09-14T11:56:44","guid":{"rendered":"https:\/\/felgenforum.shop\/?post_type=product&#038;p=87603"},"modified":"2026-04-25T15:11:36","modified_gmt":"2026-04-25T13:11:36","slug":"19-zoll-4-felgen-ff02-silber-fuer-audi-a3-s3-rs3-8p-8v-tt-tts-8j-8s-q2-ga","status":"publish","type":"product","link":"https:\/\/felgenforum.shop\/en\/product\/19-zoll-4-felgen-ff02-silber-fuer-audi-a3-s3-rs3-8p-8v-tt-tts-8j-8s-q2-ga\/","title":{"rendered":"19-inch 4 rims FF02 silver for Audi A3 S3 RS3 8P 8V TT TTS 8J 8S Q2 GA"},"content":{"rendered":"<h3>Welcome to an offer from Felgenforum.shop<\/h3>\n<p>In this offer we offer you a NEW set of FF-Wheels FF02 alloy wheels in glossy silver including ABE.<\/p>\n<p>NEW &amp; in original packaging.<\/p>\n<h3>Scope of delivery:<\/h3>\n<ul>\n<li>4 x\u00a0FF-Wheels FF02\u00a08,5&#215;19 ET45 5&#215;112\u00a0Silber\u00a0gl\u00e4nzend<\/li>\n<li>Complete mounting hardware (if required according to the ABE)<\/li>\n<li>4x Hubcaps FF-Wheels FF02<\/li>\n<li>(Vehicle manufacturer&#039;s hubcap not included)<\/li>\n<li>1x Expert report (ABE)<\/li>\n<li>In most cases, the rims are therefore registration-free. If you have any questions about fitment or any registration requirements, our experienced team will be happy to help :).<\/li>\n<li>Please be sure to specify your vehicle after purchase.<\/li>\n<li>We offer this model in many other sizes and colors; please contact us if you have any other requests.<\/li>\n<\/ul>\n<h3>&gt;&gt;&gt;Complete wheels<\/h3>\n<h3>We are happy to offer you the desired rims as ready-to-install complete wheels with a tire of your choice.<\/h3>\n<p>Feel free to send us a non-binding inquiry :).<\/p>\n<p>The rims are the correct size for the following vehicles:<\/p>\n<h3>Audi<\/h3>\n<ul>\n<li>A3 S3 8P 8P1 8V GY\u00a0<\/li>\n<li>RS3 8P 8V Sportback<\/li>\n<li>A4 S4 B8 B81<\/li>\n<li>A6 (S6 4F) 4F 4F1 C6 4G 4G1 C7 F2 C8<\/li>\n<li>A8 4E<\/li>\n<li>TT TTS TTRS 8J<\/li>\n<li>TT 8S<\/li>\n<li>Q2 SQ2 GA<\/li>\n<li>Q3 8U 8U1<\/li>\n<li>Q4 ZF<\/li>\n<\/ul>\n<h3>Volkswagen<\/h3>\n<ul>\n<li>Beetle 2<\/li>\n<li>EOS 1F<\/li>\n<li>Golf 6 7 8 in all versions<\/li>\n<li>ID.3<\/li>\n<li>ID.4<\/li>\n<li>Jetta 1KM 16 16H<\/li>\n<li>Passat B6 B7 B8 B9<\/li>\n<li>Phaeton 3D<\/li>\n<li>Tiguan 5N1<\/li>\n<li>Touran 1T<\/li>\n<li>T-ROC (R) A1<\/li>\n<\/ul>\n<h3>Mercedes Benz<\/h3>\n<ul>\n<li>A-Class W176 W177<\/li>\n<li>B Class W245 W246 W247<\/li>\n<li>C-Class W204 W205 all body styles<\/li>\n<li>CLA Class C117 C118<\/li>\n<li>E-Class W212 W213 all body styles<\/li>\n<li>CL Class C215<\/li>\n<li>EQA250 F2B<\/li>\n<li>EQB<\/li>\n<li>GLA 245G F2B<\/li>\n<li>GLB F2B<\/li>\n<li>GLK X204<\/li>\n<li>S-Class W220<\/li>\n<li>Vito 639 W447 Up to axle load 1500KG<\/li>\n<li>V Class W447 Up to axle load 1500KG<\/li>\n<li>Seat (Cupra)<\/li>\n<li>Born<\/li>\n<li>Ateca 5FP<\/li>\n<li>Leon 1P 5F KL<\/li>\n<\/ul>\n<h3>Skoda<\/h3>\n<ul>\n<li>Octavia 5E NX<\/li>\n<li>Superb 2 3 4 3T<\/li>\n<li>Yeti 5L<\/li>\n<li>Karoq NU<\/li>\n<\/ul>\n<h3>BMW<\/h3>\n<ul>\n<li>X1 F48 U11<\/li>\n<li>iX1 U11<\/li>\n<li>X2 F39<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Ein Satz (4 St\u00fcck) hochwertige Marken-Alufelgen, Modell FF02, in der Gr\u00f6\u00dfe 8,5&#215;19 Zoll, Lochkreis 112 mit 5 Loch. Professionell gepr\u00fcft und versandfertig verpackt.<\/p>","protected":false},"featured_media":87686,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1535,2011,1246,1086,1092,1717],"product_tag":[],"class_list":{"0":"post-87603","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-19-zoll-audi","7":"product_cat-19-zoll-ff02-felgen","8":"product_cat-audi","9":"product_cat-felgen","10":"product_cat-ff-wheels","11":"product_cat-ff02","12":"product_shipping_class-felge","13":"pa_anzahl-der-einheiten-1484","14":"pa_einpresstiefe-et-1508","15":"pa_fahrzeugmarke-audi","16":"pa_farbe-silber","17":"pa_felgenbreite-8-5","18":"pa_felgendesign-multi-speichen-felge","19":"pa_felgenfarbe-silber","20":"pa_felgenmaterial-aluminium","21":"pa_felgenmodell-ff02","22":"pa_hersteller-ff-wheels","23":"pa_herstellergarantie-ja-zwei-jahre","24":"pa_herstellernummer-2113","25":"pa_herstellungsland-und-regi-deutschland","26":"pa_lochkreis-1439","27":"pa_lochzahl-1447","28":"pa_maximale-traglast-750-kg","29":"pa_mit-deckel-ja-nein-ja-von-ff-wheels-2","30":"pa_modell-ff02","31":"pa_produktart-kreuzspeiche","32":"pa_zollgroesse-1448","34":"first","35":"instock","36":"taxable","37":"shipping-taxable","38":"purchasable","39":"product-type-simple"},"yoast_head":"<title>19 Zoll 4 Felgen FF02 silber f\u00fcr Audi A3 S3 RS3 8P 8V TT TTS 8J 8S Q2 GA g\u00fcnstig kaufen - Felgenforum<\/title>\n<meta name=\"description\" content=\"Werten Sie Ihren Audi auf mit 19 Zoll Felgen FF02 in Silber. Perfekte Passform f\u00fcr A3, S3, RS3, TT und Q2. Jetzt hochwertigen Felgensatz online kaufen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/felgenforum.shop\/en\/product\/19-zoll-4-felgen-ff02-silber-fuer-audi-a3-s3-rs3-8p-8v-tt-tts-8j-8s-q2-ga\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"19 Zoll 4 Felgen FF02 silber f\u00fcr Audi A3 S3 RS3 8P 8V TT TTS 8J 8S Q2 GA g\u00fcnstig kaufen - Felgenforum\" \/>\n<meta property=\"og:description\" content=\"Werten Sie Ihren Audi auf mit 19 Zoll Felgen FF02 in Silber. Perfekte Passform f\u00fcr A3, S3, RS3, TT und Q2. Jetzt hochwertigen Felgensatz online kaufen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/felgenforum.shop\/en\/product\/19-zoll-4-felgen-ff02-silber-fuer-audi-a3-s3-rs3-8p-8v-tt-tts-8j-8s-q2-ga\/\" \/>\n<meta property=\"og:site_name\" content=\"Felgenforum\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-25T13:11:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/57-4581.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1041\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-4-felgen-ff02-silber-fuer-audi-a3-s3-rs3-8p-8v-tt-tts-8j-8s-q2-ga\\\/\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-4-felgen-ff02-silber-fuer-audi-a3-s3-rs3-8p-8v-tt-tts-8j-8s-q2-ga\\\/\",\"name\":\"19 Zoll 4 Felgen FF02 silber f\u00fcr Audi A3 S3 RS3 8P 8V TT TTS 8J 8S Q2 GA g\u00fcnstig kaufen - Felgenforum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-4-felgen-ff02-silber-fuer-audi-a3-s3-rs3-8p-8v-tt-tts-8j-8s-q2-ga\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-4-felgen-ff02-silber-fuer-audi-a3-s3-rs3-8p-8v-tt-tts-8j-8s-q2-ga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/57-4581.webp\",\"datePublished\":\"2025-09-14T11:56:44+00:00\",\"dateModified\":\"2026-04-25T13:11:36+00:00\",\"description\":\"Werten Sie Ihren Audi auf mit 19 Zoll Felgen FF02 in Silber. Perfekte Passform f\u00fcr A3, S3, RS3, TT und Q2. Jetzt hochwertigen Felgensatz online kaufen!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-4-felgen-ff02-silber-fuer-audi-a3-s3-rs3-8p-8v-tt-tts-8j-8s-q2-ga\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-4-felgen-ff02-silber-fuer-audi-a3-s3-rs3-8p-8v-tt-tts-8j-8s-q2-ga\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-4-felgen-ff02-silber-fuer-audi-a3-s3-rs3-8p-8v-tt-tts-8j-8s-q2-ga\\\/#primaryimage\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/57-4581.webp\",\"contentUrl\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/57-4581.webp\",\"width\":1041,\"height\":1000,\"caption\":\"Satz silberne 19 Zoll FF02 Felgen f\u00fcr Audi A3 S3 RS3 TT Q2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-4-felgen-ff02-silber-fuer-audi-a3-s3-rs3-8p-8v-tt-tts-8j-8s-q2-ga\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/felgenforum.shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/felgenforum.shop\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"19 Zoll 4 Felgen FF02 silber f\u00fcr Audi A3 S3 RS3 8P 8V TT TTS 8J 8S Q2 GA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/#website\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/\",\"name\":\"Felgenforum\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/felgenforum.shop\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>","yoast_head_json":{"title":"19 Zoll 4 Felgen FF02 silber f\u00fcr Audi A3 S3 RS3 8P 8V TT TTS 8J 8S Q2 GA g\u00fcnstig kaufen - Felgenforum","description":"Werten Sie Ihren Audi auf mit 19 Zoll Felgen FF02 in Silber. Perfekte Passform f\u00fcr A3, S3, RS3, TT und Q2. Jetzt hochwertigen Felgensatz online kaufen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/felgenforum.shop\/en\/product\/19-zoll-4-felgen-ff02-silber-fuer-audi-a3-s3-rs3-8p-8v-tt-tts-8j-8s-q2-ga\/","og_locale":"en_GB","og_type":"article","og_title":"19 Zoll 4 Felgen FF02 silber f\u00fcr Audi A3 S3 RS3 8P 8V TT TTS 8J 8S Q2 GA g\u00fcnstig kaufen - Felgenforum","og_description":"Werten Sie Ihren Audi auf mit 19 Zoll Felgen FF02 in Silber. Perfekte Passform f\u00fcr A3, S3, RS3, TT und Q2. Jetzt hochwertigen Felgensatz online kaufen!","og_url":"https:\/\/felgenforum.shop\/en\/product\/19-zoll-4-felgen-ff02-silber-fuer-audi-a3-s3-rs3-8p-8v-tt-tts-8j-8s-q2-ga\/","og_site_name":"Felgenforum","article_modified_time":"2026-04-25T13:11:36+00:00","og_image":[{"width":1041,"height":1000,"url":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/57-4581.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-4-felgen-ff02-silber-fuer-audi-a3-s3-rs3-8p-8v-tt-tts-8j-8s-q2-ga\/","url":"https:\/\/felgenforum.shop\/produkt\/19-zoll-4-felgen-ff02-silber-fuer-audi-a3-s3-rs3-8p-8v-tt-tts-8j-8s-q2-ga\/","name":"19 Zoll 4 Felgen FF02 silber f\u00fcr Audi A3 S3 RS3 8P 8V TT TTS 8J 8S Q2 GA g\u00fcnstig kaufen - Felgenforum","isPartOf":{"@id":"https:\/\/felgenforum.shop\/#website"},"primaryImageOfPage":{"@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-4-felgen-ff02-silber-fuer-audi-a3-s3-rs3-8p-8v-tt-tts-8j-8s-q2-ga\/#primaryimage"},"image":{"@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-4-felgen-ff02-silber-fuer-audi-a3-s3-rs3-8p-8v-tt-tts-8j-8s-q2-ga\/#primaryimage"},"thumbnailUrl":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/57-4581.webp","datePublished":"2025-09-14T11:56:44+00:00","dateModified":"2026-04-25T13:11:36+00:00","description":"Werten Sie Ihren Audi auf mit 19 Zoll Felgen FF02 in Silber. Perfekte Passform f\u00fcr A3, S3, RS3, TT und Q2. Jetzt hochwertigen Felgensatz online kaufen!","breadcrumb":{"@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-4-felgen-ff02-silber-fuer-audi-a3-s3-rs3-8p-8v-tt-tts-8j-8s-q2-ga\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/felgenforum.shop\/produkt\/19-zoll-4-felgen-ff02-silber-fuer-audi-a3-s3-rs3-8p-8v-tt-tts-8j-8s-q2-ga\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-4-felgen-ff02-silber-fuer-audi-a3-s3-rs3-8p-8v-tt-tts-8j-8s-q2-ga\/#primaryimage","url":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/57-4581.webp","contentUrl":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/57-4581.webp","width":1041,"height":1000,"caption":"Satz silberne 19 Zoll FF02 Felgen f\u00fcr Audi A3 S3 RS3 TT Q2"},{"@type":"BreadcrumbList","@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-4-felgen-ff02-silber-fuer-audi-a3-s3-rs3-8p-8v-tt-tts-8j-8s-q2-ga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/felgenforum.shop\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/felgenforum.shop\/shop\/"},{"@type":"ListItem","position":3,"name":"19 Zoll 4 Felgen FF02 silber f\u00fcr Audi A3 S3 RS3 8P 8V TT TTS 8J 8S Q2 GA"}]},{"@type":"WebSite","@id":"https:\/\/felgenforum.shop\/#website","url":"https:\/\/felgenforum.shop\/","name":"Rim forum","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/felgenforum.shop\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product\/87603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/comments?post=87603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/media\/87686"}],"wp:attachment":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/media?parent=87603"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_brand?post=87603"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_cat?post=87603"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_tag?post=87603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}