{"id":86964,"date":"2025-09-14T13:11:46","date_gmt":"2025-09-14T11:11:46","guid":{"rendered":"https:\/\/felgenforum.shop\/?post_type=product&#038;p=86964"},"modified":"2026-04-25T15:11:31","modified_gmt":"2026-04-25T13:11:31","slug":"19-zoll-felgen-v2-wheels-schwarz-bmw-3er-e90-e91-e92-e93-f30-f31-f34-e46-gt-m","status":"publish","type":"product","link":"https:\/\/felgenforum.shop\/en\/product\/19-zoll-felgen-v2-wheels-schwarz-bmw-3er-e90-e91-e92-e93-f30-f31-f34-e46-gt-m\/","title":{"rendered":"19 inch rims V2 Wheels black BMW 3 series e90 e91 e92 e93 F30 F31 F34 e46 GT M"},"content":{"rendered":"<h3>Welcome to an offer from Felgenforum.shop<\/h3>\n<p>In this offer we offer you a NEW set of V1 Wheels V2 alloy rims in glossy black including ABE.<\/p>\n<p>NEW &amp; in original packaging.<\/p>\n<h3>Scope of delivery:<\/h3>\n<ul>\n<li>4 x V1 Wheels V2 8,5&#215;19 ET35 5&#215;120 schwarz gl\u00e4nzend<\/li>\n<li>Complete mounting hardware (if required according to the ABE)<\/li>\n<li>4x Hubcaps V1 Wheels<\/li>\n<li>(Vehicle manufacturer&#039;s hubcap not included)<\/li>\n<li>1x Expert report (ABE)<\/li>\n<li>In most cases, the rims are therefore registration-free. If you have any questions about fitment or any registration requirements, our experienced team will be happy to help :).<\/li>\n<li>Please be sure to specify your vehicle after purchase.<\/li>\n<li>We offer this model in many other sizes and colors; please contact us if you have any other requests.<\/li>\n<\/ul>\n<h3>&gt;&gt;&gt;Complete wheels<\/h3>\n<h3>We are happy to offer you the desired rims as ready-to-install complete wheels with a tire of your choice.<\/h3>\n<p>Feel free to send us a non-binding inquiry :).<\/p>\n<p>The rims are the correct size for the following vehicles:<\/p>\n<h3>BMW<\/h3>\n<ul>\n<li>1 Series F20 F21<\/li>\n<li>2 Series F22 F23<\/li>\n<li>3 series e90 e91 e92 e93 F30 F31 F34<\/li>\n<li>4 Series F32 F33 F36<\/li>\n<li>5 Series F10 F11<\/li>\n<li>6 Series F12 F13<\/li>\n<li>X1 E84<\/li>\n<li>X3 E83 F25<\/li>\n<li>X4 F26<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Ein Satz (4 St\u00fcck) hochwertige Marken-Alufelgen in der Gr\u00f6\u00dfe 8,5&#215;19 Zoll, Lochkreis 120 mit 5 Loch. Professionell gepr\u00fcft und versandfertig verpackt.<\/p>","protected":false},"featured_media":86965,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1561,1501,1086],"product_tag":[],"class_list":{"0":"post-86964","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-19-zoll-bmw-felgen","7":"product_cat-bmw-felgen","8":"product_cat-felgen","9":"product_shipping_class-felge","10":"pa_anzahl-der-einheiten-1484","11":"pa_einpresstiefe-et-1460","12":"pa_fahrzeugmarke-bmw","13":"pa_farbe-schwarz","14":"pa_felgenbreite-8-5","15":"pa_felgendesign-multi-speichen-felge","16":"pa_felgenfarbe-schwarz","17":"pa_felgenmaterial-aluminium","18":"pa_felgenmodell-v2","19":"pa_hersteller-v1-wheels","20":"pa_herstellergarantie-ja-zwei-jahre","21":"pa_herstellernummer-2104","22":"pa_herstellungsland-und-regi-deutschland","23":"pa_lochkreis-1494","24":"pa_lochzahl-1447","25":"pa_mit-deckel-ja-nein-ja-von-v1-wheels","26":"pa_mittenlochbohrung-1658","27":"pa_produktart-y-speiche","28":"pa_zollgroesse-1448","30":"first","31":"instock","32":"taxable","33":"shipping-taxable","34":"purchasable","35":"product-type-simple"},"yoast_head":"<title>19 Zoll Felgen V2 Wheels schwarz BMW 3er e90 e91 e92 e93 F30 F31 F34 e46 GT M g\u00fcnstig kaufen - Felgenforum<\/title>\n<meta name=\"description\" content=\"Werten Sie Ihren BMW 3er mit schwarzen 19 Zoll V2 Wheels Felgen auf. Perfekte Passform f\u00fcr E90, F30 und weitere Modelle. Jetzt online entdecken und kaufen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/felgenforum.shop\/en\/product\/19-zoll-felgen-v2-wheels-schwarz-bmw-3er-e90-e91-e92-e93-f30-f31-f34-e46-gt-m\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"19 Zoll Felgen V2 Wheels schwarz BMW 3er e90 e91 e92 e93 F30 F31 F34 e46 GT M g\u00fcnstig kaufen - Felgenforum\" \/>\n<meta property=\"og:description\" content=\"Werten Sie Ihren BMW 3er mit schwarzen 19 Zoll V2 Wheels Felgen auf. Perfekte Passform f\u00fcr E90, F30 und weitere Modelle. Jetzt online entdecken und kaufen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/felgenforum.shop\/en\/product\/19-zoll-felgen-v2-wheels-schwarz-bmw-3er-e90-e91-e92-e93-f30-f31-f34-e46-gt-m\/\" \/>\n<meta property=\"og:site_name\" content=\"Felgenforum\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-25T13:11:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/57-4499.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"966\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-v2-wheels-schwarz-bmw-3er-e90-e91-e92-e93-f30-f31-f34-e46-gt-m\\\/\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-v2-wheels-schwarz-bmw-3er-e90-e91-e92-e93-f30-f31-f34-e46-gt-m\\\/\",\"name\":\"19 Zoll Felgen V2 Wheels schwarz BMW 3er e90 e91 e92 e93 F30 F31 F34 e46 GT M g\u00fcnstig kaufen - Felgenforum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-v2-wheels-schwarz-bmw-3er-e90-e91-e92-e93-f30-f31-f34-e46-gt-m\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-v2-wheels-schwarz-bmw-3er-e90-e91-e92-e93-f30-f31-f34-e46-gt-m\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/57-4499.webp\",\"datePublished\":\"2025-09-14T11:11:46+00:00\",\"dateModified\":\"2026-04-25T13:11:31+00:00\",\"description\":\"Werten Sie Ihren BMW 3er mit schwarzen 19 Zoll V2 Wheels Felgen auf. Perfekte Passform f\u00fcr E90, F30 und weitere Modelle. Jetzt online entdecken und kaufen!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-v2-wheels-schwarz-bmw-3er-e90-e91-e92-e93-f30-f31-f34-e46-gt-m\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-v2-wheels-schwarz-bmw-3er-e90-e91-e92-e93-f30-f31-f34-e46-gt-m\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-v2-wheels-schwarz-bmw-3er-e90-e91-e92-e93-f30-f31-f34-e46-gt-m\\\/#primaryimage\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/57-4499.webp\",\"contentUrl\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/57-4499.webp\",\"width\":966,\"height\":1000,\"caption\":\"Schwarze 19 Zoll V2 Wheels Felgen f\u00fcr BMW 3er E90 F30 Modelle\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-v2-wheels-schwarz-bmw-3er-e90-e91-e92-e93-f30-f31-f34-e46-gt-m\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/felgenforum.shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/felgenforum.shop\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"19 Zoll Felgen V2 Wheels schwarz BMW 3er e90 e91 e92 e93 F30 F31 F34 e46 GT M\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/#website\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/\",\"name\":\"Felgenforum\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/felgenforum.shop\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>","yoast_head_json":{"title":"19 Zoll Felgen V2 Wheels schwarz BMW 3er e90 e91 e92 e93 F30 F31 F34 e46 GT M g\u00fcnstig kaufen - Felgenforum","description":"Werten Sie Ihren BMW 3er mit schwarzen 19 Zoll V2 Wheels Felgen auf. Perfekte Passform f\u00fcr E90, F30 und weitere Modelle. Jetzt online entdecken und kaufen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/felgenforum.shop\/en\/product\/19-zoll-felgen-v2-wheels-schwarz-bmw-3er-e90-e91-e92-e93-f30-f31-f34-e46-gt-m\/","og_locale":"en_GB","og_type":"article","og_title":"19 Zoll Felgen V2 Wheels schwarz BMW 3er e90 e91 e92 e93 F30 F31 F34 e46 GT M g\u00fcnstig kaufen - Felgenforum","og_description":"Werten Sie Ihren BMW 3er mit schwarzen 19 Zoll V2 Wheels Felgen auf. Perfekte Passform f\u00fcr E90, F30 und weitere Modelle. Jetzt online entdecken und kaufen!","og_url":"https:\/\/felgenforum.shop\/en\/product\/19-zoll-felgen-v2-wheels-schwarz-bmw-3er-e90-e91-e92-e93-f30-f31-f34-e46-gt-m\/","og_site_name":"Felgenforum","article_modified_time":"2026-04-25T13:11:31+00:00","og_image":[{"width":966,"height":1000,"url":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/57-4499.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-v2-wheels-schwarz-bmw-3er-e90-e91-e92-e93-f30-f31-f34-e46-gt-m\/","url":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-v2-wheels-schwarz-bmw-3er-e90-e91-e92-e93-f30-f31-f34-e46-gt-m\/","name":"19 Zoll Felgen V2 Wheels schwarz BMW 3er e90 e91 e92 e93 F30 F31 F34 e46 GT M g\u00fcnstig kaufen - Felgenforum","isPartOf":{"@id":"https:\/\/felgenforum.shop\/#website"},"primaryImageOfPage":{"@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-v2-wheels-schwarz-bmw-3er-e90-e91-e92-e93-f30-f31-f34-e46-gt-m\/#primaryimage"},"image":{"@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-v2-wheels-schwarz-bmw-3er-e90-e91-e92-e93-f30-f31-f34-e46-gt-m\/#primaryimage"},"thumbnailUrl":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/57-4499.webp","datePublished":"2025-09-14T11:11:46+00:00","dateModified":"2026-04-25T13:11:31+00:00","description":"Werten Sie Ihren BMW 3er mit schwarzen 19 Zoll V2 Wheels Felgen auf. Perfekte Passform f\u00fcr E90, F30 und weitere Modelle. Jetzt online entdecken und kaufen!","breadcrumb":{"@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-v2-wheels-schwarz-bmw-3er-e90-e91-e92-e93-f30-f31-f34-e46-gt-m\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-v2-wheels-schwarz-bmw-3er-e90-e91-e92-e93-f30-f31-f34-e46-gt-m\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-v2-wheels-schwarz-bmw-3er-e90-e91-e92-e93-f30-f31-f34-e46-gt-m\/#primaryimage","url":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/57-4499.webp","contentUrl":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/57-4499.webp","width":966,"height":1000,"caption":"Schwarze 19 Zoll V2 Wheels Felgen f\u00fcr BMW 3er E90 F30 Modelle"},{"@type":"BreadcrumbList","@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-v2-wheels-schwarz-bmw-3er-e90-e91-e92-e93-f30-f31-f34-e46-gt-m\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/felgenforum.shop\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/felgenforum.shop\/shop\/"},{"@type":"ListItem","position":3,"name":"19 Zoll Felgen V2 Wheels schwarz BMW 3er e90 e91 e92 e93 F30 F31 F34 e46 GT M"}]},{"@type":"WebSite","@id":"https:\/\/felgenforum.shop\/#website","url":"https:\/\/felgenforum.shop\/","name":"Rim forum","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/felgenforum.shop\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product\/86964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/comments?post=86964"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/media\/86965"}],"wp:attachment":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/media?parent=86964"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_brand?post=86964"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_cat?post=86964"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_tag?post=86964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}