{"id":83522,"date":"2025-09-14T00:17:07","date_gmt":"2025-09-13T22:17:07","guid":{"rendered":"https:\/\/felgenforum.shop\/?post_type=product&#038;p=83522"},"modified":"2026-04-25T15:09:58","modified_gmt":"2026-04-25T13:09:58","slug":"18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo","status":"publish","type":"product","link":"https:\/\/felgenforum.shop\/en\/product\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo\/","title":{"rendered":"18-inch FF Wheels FF01 bronze rims for Audi A3 S3 8P 8V 8Y GY Sportback Sedan"},"content":{"rendered":"<h3>Welcome to an offer from Felgenforum.shop<\/h3>\n<p>In this offer we offer you a NEW set of FF Wheels FF01 18 inch alloy wheels in matte bronze including ABE.<\/p>\n<p>NEW &amp; in original packaging.<\/p>\n<h3>Scope of delivery:<\/h3>\n<ul>\n<li>4 x FF Wheels FF01 8\u00d718 ET45 5\u00d7112 matt bronze<\/li>\n<li>Complete mounting hardware (if required according to the ABE)<\/li>\n<li>4x Hubcaps FF Wheels<\/li>\n<li>(Vehicle manufacturer&#039;s hubcap not included)<\/li>\n<li>1x Expert report (ABE)<\/li>\n<li>In most cases, the rims are therefore registration-free. If you have any questions about fitment or any registration requirements, our experienced team will be happy to help :).<\/li>\n<li>Please be sure to specify your vehicle after purchase.<\/li>\n<li>We offer this model in many other sizes and colors; please contact us if you have any other requests.<\/li>\n<\/ul>\n<h3>&gt;&gt;&gt;Complete wheels<\/h3>\n<h3>We are happy to offer you the desired rims as ready-to-install complete wheels with a tire of your choice.<\/h3>\n<p>Feel free to send us a non-binding inquiry :).<\/p>\n<p>The rims are the correct size for the following vehicles:<\/p>\n<h3>Audi<\/h3>\n<ul>\n<li>A3 S3 8P 8P1 8V GY\u00a0<\/li>\n<li>A4 S4 B6 B7 B8 B81 8E 8H<\/li>\n<li>A6 4F 4F1 C6 4G 4G1 C7 F2 C8<\/li>\n<li>A8 4E<\/li>\n<li>TT (TTS 8J) 8J 8S FV<\/li>\n<li>TTRS 8J<\/li>\n<li>Q2 GA<\/li>\n<li>Q3 8U 8U1<\/li>\n<\/ul>\n<h3>Volkswagen<\/h3>\n<ul>\n<li>Beetle 2<\/li>\n<li>EOS<\/li>\n<li>Golf 5 6 7 8 in all versions<\/li>\n<li>ID.3<\/li>\n<li>ID.4 Pure<\/li>\n<li>Jetta 1KM 16 16H<\/li>\n<li>Passat B6 B7 B8 B9<\/li>\n<li>Phaeton 3D<\/li>\n<li>Tiguan 5N1<\/li>\n<li>Touran 1T<\/li>\n<li>T-ROC (R) A1<\/li>\n<\/ul>\n<h3>Mercedes Benz<\/h3>\n<ul>\n<li>A-Class W169 W176 W177<\/li>\n<li>B Class W245 W246 W247<\/li>\n<li>C-Class W204 W205 W206 all body styles<\/li>\n<li>CLA Class C117 C118<\/li>\n<li>E-Class W212 W213 all body styles<\/li>\n<li>CL Class C215<\/li>\n<li>EQA F2B<\/li>\n<li>EQB F2B<\/li>\n<li>GLA 245G F2B<\/li>\n<li>GLB F2B<\/li>\n<li>GLK X204<\/li>\n<li>S-Class W220<\/li>\n<li>Vito 639 W447 (axle load up to 1500KG)<\/li>\n<li>V Class W447 (axle load up to 1500KG)<\/li>\n<li>Seat<\/li>\n<li>Cupra Born<\/li>\n<li>Ateca 5FP also Cupra<\/li>\n<li>Leon 1P 5F KL also Cupra<\/li>\n<\/ul>\n<h3>Skoda<\/h3>\n<ul>\n<li>Enyaq 50 60<\/li>\n<li>Karoq NU<\/li>\n<li>Octavia 1Z 5E NX<\/li>\n<li>Superb 2 3 4 3T<\/li>\n<li>Yeti 5L<\/li>\n<\/ul>\n<h3>BMW<\/h3>\n<ul>\n<li>1 Series F40<\/li>\n<li>2 Series F44 F45 F46 U06<\/li>\n<li>iX1<\/li>\n<li>X1 F48 U11<\/li>\n<li>X2 F39<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Ein Satz (4 St\u00fcck) hochwertige Marken-Alufelgen, Modell FF01, in der Gr\u00f6\u00dfe 8&#215;18 Zoll, Lochkreis 112 mm mit 5 Loch. Professionell gepr\u00fcft und versandfertig verpackt.<\/p>","protected":false},"featured_media":94051,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1427,1092,1236],"product_tag":[],"class_list":{"0":"post-83522","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-18-zoll-ff01-felgen","7":"product_cat-ff-wheels","8":"product_cat-ff01","9":"product_shipping_class-felge","10":"pa_anzahl-der-einheiten-1484","11":"pa_einpresstiefe-et-1508","12":"pa_fahrzeugmarke-audi","13":"pa_farbe-bronze","14":"pa_felgenaufbau-einteilig-gegossen","15":"pa_felgenbreite-1474","16":"pa_felgendesign-5-speichen","17":"pa_felgenfarbe-bronze","18":"pa_felgenmaterial-aluminium","19":"pa_felgenmodell-ff01","20":"pa_hersteller-ff-wheels","21":"pa_herstellergarantie-2-jahre","22":"pa_herstellernummer-1903","23":"pa_im-lieferumfang-enthalten-nabendeckel","24":"pa_kompatibler-radschraubent-radbolzen","25":"pa_lochkreis-1439","26":"pa_lochzahl-1447","27":"pa_maximale-traglast-750-kg","28":"pa_mittenlochbohrung-666-mm","29":"pa_modell-ff01","30":"pa_zollgroesse-1482","32":"first","33":"instock","34":"taxable","35":"shipping-taxable","36":"purchasable","37":"product-type-simple"},"yoast_head":"<title>18 Zoll Felgen FF Wheels FF01 bronze f\u00fcr Audi A3 S3 8P 8V 8Y GY Sportback Limo g\u00fcnstig kaufen - Felgenforum<\/title>\n<meta name=\"description\" content=\"18 Zoll Felgen FF Wheels FF01 bronze f\u00fcr Audi A3 S3 8P 8V 8Y GY Sportback Limo online bestellen \u2794 Gepr\u00fcfte Qualit\u00e4t, Top Marken &amp; schneller Versand \u2714 Jetzt sicher bei Felgenforum kaufen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/felgenforum.shop\/en\/product\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"18 Zoll Felgen FF Wheels FF01 bronze f\u00fcr Audi A3 S3 8P 8V 8Y GY Sportback Limo g\u00fcnstig kaufen - Felgenforum\" \/>\n<meta property=\"og:description\" content=\"18 Zoll Felgen FF Wheels FF01 bronze f\u00fcr Audi A3 S3 8P 8V 8Y GY Sportback Limo online bestellen \u2794 Gepr\u00fcfte Qualit\u00e4t, Top Marken &amp; schneller Versand \u2714 Jetzt sicher bei Felgenforum kaufen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/felgenforum.shop\/en\/product\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo\/\" \/>\n<meta property=\"og:site_name\" content=\"Felgenforum\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-25T13:09:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo-featured-1000px.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo\\\/\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo\\\/\",\"name\":\"18 Zoll Felgen FF Wheels FF01 bronze f\u00fcr Audi A3 S3 8P 8V 8Y GY Sportback Limo g\u00fcnstig kaufen - Felgenforum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo-featured-1000px.webp\",\"datePublished\":\"2025-09-13T22:17:07+00:00\",\"dateModified\":\"2026-04-25T13:09:58+00:00\",\"description\":\"18 Zoll Felgen FF Wheels FF01 bronze f\u00fcr Audi A3 S3 8P 8V 8Y GY Sportback Limo online bestellen \u2794 Gepr\u00fcfte Qualit\u00e4t, Top Marken & schneller Versand \u2714 Jetzt sicher bei Felgenforum kaufen!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo-featured-1000px.webp\",\"contentUrl\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo-featured-1000px.webp\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/felgenforum.shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/felgenforum.shop\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"18 Zoll Felgen FF Wheels FF01 bronze f\u00fcr Audi A3 S3 8P 8V 8Y GY Sportback Limo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/#website\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/\",\"name\":\"Felgenforum\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/felgenforum.shop\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>","yoast_head_json":{"title":"18 Zoll Felgen FF Wheels FF01 bronze f\u00fcr Audi A3 S3 8P 8V 8Y GY Sportback Limo g\u00fcnstig kaufen - Felgenforum","description":"18 Zoll Felgen FF Wheels FF01 bronze f\u00fcr Audi A3 S3 8P 8V 8Y GY Sportback Limo online bestellen \u2794 Gepr\u00fcfte Qualit\u00e4t, Top Marken & schneller Versand \u2714 Jetzt sicher bei Felgenforum kaufen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/felgenforum.shop\/en\/product\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo\/","og_locale":"en_GB","og_type":"article","og_title":"18 Zoll Felgen FF Wheels FF01 bronze f\u00fcr Audi A3 S3 8P 8V 8Y GY Sportback Limo g\u00fcnstig kaufen - Felgenforum","og_description":"18 Zoll Felgen FF Wheels FF01 bronze f\u00fcr Audi A3 S3 8P 8V 8Y GY Sportback Limo online bestellen \u2794 Gepr\u00fcfte Qualit\u00e4t, Top Marken & schneller Versand \u2714 Jetzt sicher bei Felgenforum kaufen!","og_url":"https:\/\/felgenforum.shop\/en\/product\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo\/","og_site_name":"Felgenforum","article_modified_time":"2026-04-25T13:09:58+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo-featured-1000px.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/felgenforum.shop\/produkt\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo\/","url":"https:\/\/felgenforum.shop\/produkt\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo\/","name":"18 Zoll Felgen FF Wheels FF01 bronze f\u00fcr Audi A3 S3 8P 8V 8Y GY Sportback Limo g\u00fcnstig kaufen - Felgenforum","isPartOf":{"@id":"https:\/\/felgenforum.shop\/#website"},"primaryImageOfPage":{"@id":"https:\/\/felgenforum.shop\/produkt\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo\/#primaryimage"},"image":{"@id":"https:\/\/felgenforum.shop\/produkt\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo\/#primaryimage"},"thumbnailUrl":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo-featured-1000px.webp","datePublished":"2025-09-13T22:17:07+00:00","dateModified":"2026-04-25T13:09:58+00:00","description":"18 Zoll Felgen FF Wheels FF01 bronze f\u00fcr Audi A3 S3 8P 8V 8Y GY Sportback Limo online bestellen \u2794 Gepr\u00fcfte Qualit\u00e4t, Top Marken & schneller Versand \u2714 Jetzt sicher bei Felgenforum kaufen!","breadcrumb":{"@id":"https:\/\/felgenforum.shop\/produkt\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/felgenforum.shop\/produkt\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/felgenforum.shop\/produkt\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo\/#primaryimage","url":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo-featured-1000px.webp","contentUrl":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo-featured-1000px.webp","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/felgenforum.shop\/produkt\/18-zoll-felgen-ff-wheels-ff01-bronze-fuer-audi-a3-s3-8p-8v-8y-gy-sportback-limo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/felgenforum.shop\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/felgenforum.shop\/shop\/"},{"@type":"ListItem","position":3,"name":"18 Zoll Felgen FF Wheels FF01 bronze f\u00fcr Audi A3 S3 8P 8V 8Y GY Sportback Limo"}]},{"@type":"WebSite","@id":"https:\/\/felgenforum.shop\/#website","url":"https:\/\/felgenforum.shop\/","name":"Rim forum","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/felgenforum.shop\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product\/83522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/comments?post=83522"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/media\/94051"}],"wp:attachment":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/media?parent=83522"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_brand?post=83522"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_cat?post=83522"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_tag?post=83522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}