{"id":83052,"date":"2025-09-13T22:42:00","date_gmt":"2025-09-13T20:42:00","guid":{"rendered":"https:\/\/felgenforum.shop\/?post_type=product&#038;p=83052"},"modified":"2026-04-25T15:09:44","modified_gmt":"2026-04-25T13:09:44","slug":"20-zoll-felgen-ff-wheels-ff01-grau-fuer-seat-tarraco-fr-skoda-kodiaq-ns-ps-neu","status":"publish","type":"product","link":"https:\/\/felgenforum.shop\/en\/product\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-seat-tarraco-fr-skoda-kodiaq-ns-ps-neu\/","title":{"rendered":"20-inch FF Wheels FF01 grey rims for Seat Tarraco FR Skoda Kodiaq NS PS NEW"},"content":{"rendered":"<h3>Welcome to an offer from Felgenforum.shop<\/h3>\n<p>In this offer we offer you a NEW set of FF Wheels FF01 alloy wheels in matte grey including ABE.<\/p>\n<p>NEW &amp; in original packaging.<\/p>\n<h3>Scope of delivery:<\/h3>\n<ul>\n<li>4 x FF Wheels FF01 8,5&#215;20 ET35 5&#215;112 grau matt<\/li>\n<li>Complete mounting hardware (if required according to the ABE)<\/li>\n<li>4x Hubcaps FF Wheels<\/li>\n<li>1x Expert report (ABE)<\/li>\n<li>In most cases, the rims are therefore registration-free. If you have any questions about fitment or any registration requirements, our experienced team will be happy to help :).<\/li>\n<li>Please be sure to specify your vehicle after purchase.<\/li>\n<li>We offer this model in many other sizes and colors; please contact us if you have any other requests.<\/li>\n<\/ul>\n<h3>&gt;&gt;&gt;Complete wheels<\/h3>\n<h3>We are happy to offer you the desired rims as ready-to-install complete wheels with a tire of your choice.<\/h3>\n<p>Feel free to send us a non-binding inquiry :).<\/p>\n<p>The rims are the correct size for the following vehicles:<\/p>\n<h3>Audi<\/h3>\n<ul>\n<li>A4 S4 B8 B9<\/li>\n<li>A5 S5 B8 B9<\/li>\n<li>A6 S6 4F 4F1 C6 4G 4G1 C7 F2 C8<\/li>\n<li>A7 S7 4G 4G1<\/li>\n<li>A8 4E 4H F8<\/li>\n<li>Q3 8U FY<\/li>\n<li>Q5 SQ5 8R FY<\/li>\n<\/ul>\n<h3>Volkswagen<\/h3>\n<ul>\n<li>Beetle 2<\/li>\n<li>Arteon 3H<\/li>\n<li>Passat B8 B9<\/li>\n<li>Passat CC<\/li>\n<li>Sirocco<\/li>\n<li>Phaeton 3D<\/li>\n<li>Tiguan 5N1 5N2 CT<\/li>\n<\/ul>\n<h3>Mercedes Benz<\/h3>\n<ul>\n<li>E-Class W211 W213 S213 W214 S214<\/li>\n<li>CLS W218<\/li>\n<li>CL Class C215 C216<\/li>\n<li>S-Class W221 W222<\/li>\n<li>SL R230 R231<\/li>\n<li>GLC 253 254<\/li>\n<li>Seat<\/li>\n<li>Tarraco<\/li>\n<li>Cupra Formentor<\/li>\n<li>Cupra Terramar<\/li>\n<li>Cupra Tavascan<\/li>\n<\/ul>\n<h3>Skoda<\/h3>\n<ul>\n<li>Kodiaq<\/li>\n<\/ul>\n<h3>BMW<\/h3>\n<ul>\n<li>X3 G01<\/li>\n<li>X4 G02<\/li>\n<li>4 Series G26 Gran Coupe<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>A set (4 pieces) of high-quality brand-name alloy wheels, model FF01, size 8.5Jx20 inches, bolt pattern 112 with 5 holes. Professionally inspected and packaged ready for shipping.<\/p>","protected":false},"featured_media":83053,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1649,1086,1487],"product_tag":[],"class_list":{"0":"post-83052","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-20-zoll-seat-cupra-felgen","7":"product_cat-felgen","8":"product_cat-seat-cupra-felgen","9":"product_shipping_class-felge","10":"pa_anzahl-der-einheiten-1484","11":"pa_einpresstiefe-et-1460","12":"pa_fahrzeugmarke-seat","13":"pa_farbe-grau","14":"pa_felgenaufbau-einteilig-gegossen","15":"pa_felgenbreite-8-5","16":"pa_felgendesign-5-speichen","17":"pa_felgenfarbe-grau","18":"pa_felgenmaterial-aluminium","19":"pa_felgenmodell-ff01","20":"pa_hersteller-ff-wheels","21":"pa_herstellergarantie-ja-zwei-jahre","22":"pa_herstellernummer-1900","23":"pa_herstellungsland-und-regi-deutschland","24":"pa_lochkreis-1439","25":"pa_lochzahl-1447","26":"pa_maximale-traglast-750-kg","27":"pa_mit-deckel-ja-nein-ja-von-damina","28":"pa_mittenlochbohrung-1551","29":"pa_modell-ff01","30":"pa_produktart-vielspeiche","31":"pa_zollgroesse-1499","33":"first","34":"instock","35":"taxable","36":"shipping-taxable","37":"purchasable","38":"product-type-simple"},"yoast_head":"<title>20 Zoll Felgen FF Wheels FF01 grau f\u00fcr Seat Tarraco FR Skoda Kodiaq NS PS NEU g\u00fcnstig kaufen - Felgenforum<\/title>\n<meta name=\"description\" content=\"20 Zoll Felgen FF Wheels FF01 grau f\u00fcr Seat Tarraco FR Skoda Kodiaq NS PS NEU online bestellen \u2794 Gepr\u00fcfte Qualit\u00e4t, Top Marken &amp; schneller Versand \u2714 Jetzt sicher bei Felgenforum kaufen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/felgenforum.shop\/en\/product\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-seat-tarraco-fr-skoda-kodiaq-ns-ps-neu\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"20 Zoll Felgen FF Wheels FF01 grau f\u00fcr Seat Tarraco FR Skoda Kodiaq NS PS NEU g\u00fcnstig kaufen - Felgenforum\" \/>\n<meta property=\"og:description\" content=\"20 Zoll Felgen FF Wheels FF01 grau f\u00fcr Seat Tarraco FR Skoda Kodiaq NS PS NEU online bestellen \u2794 Gepr\u00fcfte Qualit\u00e4t, Top Marken &amp; schneller Versand \u2714 Jetzt sicher bei Felgenforum kaufen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/felgenforum.shop\/en\/product\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-seat-tarraco-fr-skoda-kodiaq-ns-ps-neu\/\" \/>\n<meta property=\"og:site_name\" content=\"Felgenforum\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-25T13:09:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/57-2437.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1050\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-seat-tarraco-fr-skoda-kodiaq-ns-ps-neu\\\/\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-seat-tarraco-fr-skoda-kodiaq-ns-ps-neu\\\/\",\"name\":\"20 Zoll Felgen FF Wheels FF01 grau f\u00fcr Seat Tarraco FR Skoda Kodiaq NS PS NEU g\u00fcnstig kaufen - Felgenforum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-seat-tarraco-fr-skoda-kodiaq-ns-ps-neu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-seat-tarraco-fr-skoda-kodiaq-ns-ps-neu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/57-2437.webp\",\"datePublished\":\"2025-09-13T20:42:00+00:00\",\"dateModified\":\"2026-04-25T13:09:44+00:00\",\"description\":\"20 Zoll Felgen FF Wheels FF01 grau f\u00fcr Seat Tarraco FR Skoda Kodiaq NS PS NEU online bestellen \u2794 Gepr\u00fcfte Qualit\u00e4t, Top Marken & schneller Versand \u2714 Jetzt sicher bei Felgenforum kaufen!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-seat-tarraco-fr-skoda-kodiaq-ns-ps-neu\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-seat-tarraco-fr-skoda-kodiaq-ns-ps-neu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-seat-tarraco-fr-skoda-kodiaq-ns-ps-neu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/57-2437.webp\",\"contentUrl\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/57-2437.webp\",\"width\":1050,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-seat-tarraco-fr-skoda-kodiaq-ns-ps-neu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/felgenforum.shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/felgenforum.shop\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"20 Zoll Felgen FF Wheels FF01 grau f\u00fcr Seat Tarraco FR Skoda Kodiaq NS PS NEU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/#website\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/\",\"name\":\"Felgenforum\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/felgenforum.shop\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>","yoast_head_json":{"title":"20 Zoll Felgen FF Wheels FF01 grau f\u00fcr Seat Tarraco FR Skoda Kodiaq NS PS NEU g\u00fcnstig kaufen - Felgenforum","description":"20 Zoll Felgen FF Wheels FF01 grau f\u00fcr Seat Tarraco FR Skoda Kodiaq NS PS NEU online bestellen \u2794 Gepr\u00fcfte Qualit\u00e4t, Top Marken & schneller Versand \u2714 Jetzt sicher bei Felgenforum kaufen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/felgenforum.shop\/en\/product\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-seat-tarraco-fr-skoda-kodiaq-ns-ps-neu\/","og_locale":"en_GB","og_type":"article","og_title":"20 Zoll Felgen FF Wheels FF01 grau f\u00fcr Seat Tarraco FR Skoda Kodiaq NS PS NEU g\u00fcnstig kaufen - Felgenforum","og_description":"20 Zoll Felgen FF Wheels FF01 grau f\u00fcr Seat Tarraco FR Skoda Kodiaq NS PS NEU online bestellen \u2794 Gepr\u00fcfte Qualit\u00e4t, Top Marken & schneller Versand \u2714 Jetzt sicher bei Felgenforum kaufen!","og_url":"https:\/\/felgenforum.shop\/en\/product\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-seat-tarraco-fr-skoda-kodiaq-ns-ps-neu\/","og_site_name":"Felgenforum","article_modified_time":"2026-04-25T13:09:44+00:00","og_image":[{"width":1050,"height":1000,"url":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/57-2437.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/felgenforum.shop\/produkt\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-seat-tarraco-fr-skoda-kodiaq-ns-ps-neu\/","url":"https:\/\/felgenforum.shop\/produkt\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-seat-tarraco-fr-skoda-kodiaq-ns-ps-neu\/","name":"20 Zoll Felgen FF Wheels FF01 grau f\u00fcr Seat Tarraco FR Skoda Kodiaq NS PS NEU g\u00fcnstig kaufen - Felgenforum","isPartOf":{"@id":"https:\/\/felgenforum.shop\/#website"},"primaryImageOfPage":{"@id":"https:\/\/felgenforum.shop\/produkt\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-seat-tarraco-fr-skoda-kodiaq-ns-ps-neu\/#primaryimage"},"image":{"@id":"https:\/\/felgenforum.shop\/produkt\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-seat-tarraco-fr-skoda-kodiaq-ns-ps-neu\/#primaryimage"},"thumbnailUrl":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/57-2437.webp","datePublished":"2025-09-13T20:42:00+00:00","dateModified":"2026-04-25T13:09:44+00:00","description":"20 Zoll Felgen FF Wheels FF01 grau f\u00fcr Seat Tarraco FR Skoda Kodiaq NS PS NEU online bestellen \u2794 Gepr\u00fcfte Qualit\u00e4t, Top Marken & schneller Versand \u2714 Jetzt sicher bei Felgenforum kaufen!","breadcrumb":{"@id":"https:\/\/felgenforum.shop\/produkt\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-seat-tarraco-fr-skoda-kodiaq-ns-ps-neu\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/felgenforum.shop\/produkt\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-seat-tarraco-fr-skoda-kodiaq-ns-ps-neu\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/felgenforum.shop\/produkt\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-seat-tarraco-fr-skoda-kodiaq-ns-ps-neu\/#primaryimage","url":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/57-2437.webp","contentUrl":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/57-2437.webp","width":1050,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/felgenforum.shop\/produkt\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-seat-tarraco-fr-skoda-kodiaq-ns-ps-neu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/felgenforum.shop\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/felgenforum.shop\/shop\/"},{"@type":"ListItem","position":3,"name":"20 Zoll Felgen FF Wheels FF01 grau f\u00fcr Seat Tarraco FR Skoda Kodiaq NS PS NEU"}]},{"@type":"WebSite","@id":"https:\/\/felgenforum.shop\/#website","url":"https:\/\/felgenforum.shop\/","name":"Rim forum","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/felgenforum.shop\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product\/83052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/comments?post=83052"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/media\/83053"}],"wp:attachment":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/media?parent=83052"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_brand?post=83052"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_cat?post=83052"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_tag?post=83052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}