{"id":227170,"date":"2026-03-05T00:38:22","date_gmt":"2026-03-04T23:38:22","guid":{"rendered":"https:\/\/felgenforum.shop\/?post_type=product&#038;p=227170"},"modified":"2026-04-25T15:25:04","modified_gmt":"2026-04-25T13:25:04","slug":"19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-10","status":"publish","type":"product","link":"https:\/\/felgenforum.shop\/en\/product\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-10\/","title":{"rendered":"19-inch summer wheels, summer tires 245\/45, Mercedes E-Class All-Terrain S213 213"},"content":{"rendered":"<p>\u00a0Welcome to an offer from Felgenforum.shop<\/p>\n<p>In this offer we offer you a NEW set of summer complete wheels in polished black including ABE.<\/p>\n<p>4x fully pre-assembled and balanced complete wheels<\/p>\n<p>consisting of:<\/p>\n<p>4x Alufelge Wheelworld WH39 schwarz poliert 8,5&#215;19 ET35 LK5\/112<\/p>\n<p>+<\/p>\n<p>4x summer tires 245\/45 R19 102Y from current daily purchase<\/p>\n<p>fully assembled and balanced\u00a0<\/p>\n<p>+<\/p>\n<p>4x TPMS (pre-programmed)<\/p>\n<p>(including black weights and black metal valves)<\/p>\n<p>NEW<\/p>\n<h3>Scope of delivery:<\/h3>\n<ul>\n<li>4 x Wheelworld WH39 8,5&#215;19 ET35 5&#215;112 schwarz poliert<\/li>\n<li>Complete mounting hardware (if required according to the ABE)<\/li>\n<li>4x summer tires from current daily purchase 245\/45 R19 102Y<\/li>\n<li>4x TPMS (pre-programmed)<\/li>\n<li>4x Wheelworld hubcaps<\/li>\n<li>(Vehicle manufacturer&#039;s hubcap not included)<\/li>\n<li>1x Expert report (ABE)<\/li>\n<li>In most cases, the complete wheel sets are therefore registration-free. If you have any questions about fitment or any registration requirements, our experienced team will be happy to assist you :).<\/li>\n<li>Please be sure to specify your vehicle after purchase.<\/li>\n<li>We offer this model in many other sizes and colors; please contact us if you have any other requests.<\/li>\n<li>&gt;&gt;&gt;Wishful tires<\/li>\n<li>Do you have a specific request regarding tire brand or tire quality? No problem!<\/li>\n<li>We would be happy to create individual complete wheel offers for you :).<\/li>\n<li>The complete wheels are suitable for, among others:<\/li>\n<\/ul>\n<h3>Audi<\/h3>\n<ul>\n<li>A6 S6 C8 F2<\/li>\n<li>A6 Allroad C7 4G C8 F2<\/li>\n<li>A8 S8 4H F8 D4 D5<\/li>\n<li>Q3 RSQ3 F3<\/li>\n<li>Seat<\/li>\n<li>Tarraco (FR)<\/li>\n<\/ul>\n<h3>Skoda<\/h3>\n<ul>\n<li>Kodiaq<\/li>\n<li>Mercedes<\/li>\n<li>E-Class All-Terrain W213<\/li>\n<li>S-Class W222<\/li>\n<li>S-Class Coupe Cabriolet C217 A217<\/li>\n<li>VW<\/li>\n<li>Tiguan (R)<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>A set (4 pieces) of ready-to-drive Wheelworld complete wheels, professionally mounted and balanced.<\/p>\n<p><strong>Rim details:<\/strong> 8,5&#215;19 Zoll, Lochkreis 112.<br \/><strong>Tire details:<\/strong> Daily shopping, tread depth: approx. NEW mm.<\/p>","protected":false},"featured_media":227384,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1471,1196,1470],"product_tag":[],"class_list":{"0":"post-227170","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-19-zoll-sommerraeder-mercedes-mercedes-komplettraeder-sommer","7":"product_cat-komplettraeder-sommer","8":"product_cat-mercedes-komplettraeder-sommer","9":"product_shipping_class-komplettrad","10":"pa_anzahl-der-komplettraeder-1433","11":"pa_einpresstiefe-et-1460","12":"pa_eisgriffigkeit-nein","13":"pa_fahrzeugmarke-mercedes","14":"pa_fahrzeugtyp-allradfahrzeug","15":"pa_felgenaufbau-einteilig-gegossen","16":"pa_felgenbreite-8-5","17":"pa_felgendesign-multi-speichen-felge","18":"pa_felgenfarbe-schwarz-poliert","19":"pa_felgenhersteller-wheelworld","20":"pa_felgenmaterial-aluminium","21":"pa_felgenmodell-wh39","22":"pa_geschwindigkeitsindex-v-bis-240-km-h","23":"pa_herstellergarantie-2-jahre","24":"pa_herstellernummer-felge-2526","25":"pa_lastbereich-xl","26":"pa_lochkreis-1439","27":"pa_lochzahl-1447","28":"pa_mittenlochbohrung-666-mm","29":"pa_profiltiefe-neu","30":"pa_reifenbauart-r-radialreifen","31":"pa_reifenbreite-1503","32":"pa_reifendurchmesser-1436","33":"pa_reifenhersteller-tageseinkauf","34":"pa_reifenmodell-tageseinkauf","35":"pa_reifenquerschnitt-1504","36":"pa_reifenspezifikation-sommerreifen","37":"pa_run-flat-nein","38":"pa_schneeflocken-symbol-nein","39":"pa_tragfaehigkeitsindex-102-max-850-kg-je-reifen","40":"pa_zollgroesse-1448","42":"first","43":"instock","44":"sale","45":"taxable","46":"shipping-taxable","47":"purchasable","48":"product-type-simple"},"yoast_head":"<title>19 Zoll Sommerr\u00e4der Sommerreifen 245\/45 Mercedes E Klasse All terrain S213 213 g\u00fcnstig kaufen - Felgenforum<\/title>\n<meta name=\"description\" content=\"19 Zoll Sommerr\u00e4der Sommerreifen 245\/45 Mercedes E Klasse All terrain S213 213 online bestellen \u2794 Gepr\u00fcfte Qualit\u00e4t, Top Marken &amp; schneller Versand \u2714 Jetzt sicher bei Felgenforum kaufen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/felgenforum.shop\/en\/product\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-10\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"19 Zoll Sommerr\u00e4der Sommerreifen 245\/45 Mercedes E Klasse All terrain S213 213 g\u00fcnstig kaufen - Felgenforum\" \/>\n<meta property=\"og:description\" content=\"19 Zoll Sommerr\u00e4der Sommerreifen 245\/45 Mercedes E Klasse All terrain S213 213 online bestellen \u2794 Gepr\u00fcfte Qualit\u00e4t, Top Marken &amp; schneller Versand \u2714 Jetzt sicher bei Felgenforum kaufen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/felgenforum.shop\/en\/product\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-10\/\" \/>\n<meta property=\"og:site_name\" content=\"Felgenforum\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-25T13:25:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/felgenforum.shop\/wp-content\/uploads\/2026\/03\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-featured-1000px.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-10\\\/\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-10\\\/\",\"name\":\"19 Zoll Sommerr\u00e4der Sommerreifen 245\\\/45 Mercedes E Klasse All terrain S213 213 g\u00fcnstig kaufen - Felgenforum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-10\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-10\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-featured-1000px.webp\",\"datePublished\":\"2026-03-04T23:38:22+00:00\",\"dateModified\":\"2026-04-25T13:25:04+00:00\",\"description\":\"19 Zoll Sommerr\u00e4der Sommerreifen 245\\\/45 Mercedes E Klasse All terrain S213 213 online bestellen \u2794 Gepr\u00fcfte Qualit\u00e4t, Top Marken & schneller Versand \u2714 Jetzt sicher bei Felgenforum kaufen!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-10\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-10\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-10\\\/#primaryimage\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-featured-1000px.webp\",\"contentUrl\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-featured-1000px.webp\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-10\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/felgenforum.shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/felgenforum.shop\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"19 Zoll Sommerr\u00e4der Sommerreifen 245\\\/45 Mercedes E Klasse All terrain S213 213\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/#website\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/\",\"name\":\"Felgenforum\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/felgenforum.shop\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>","yoast_head_json":{"title":"19 Zoll Sommerr\u00e4der Sommerreifen 245\/45 Mercedes E Klasse All terrain S213 213 g\u00fcnstig kaufen - Felgenforum","description":"19 Zoll Sommerr\u00e4der Sommerreifen 245\/45 Mercedes E Klasse All terrain S213 213 online bestellen \u2794 Gepr\u00fcfte Qualit\u00e4t, Top Marken & schneller Versand \u2714 Jetzt sicher bei Felgenforum kaufen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/felgenforum.shop\/en\/product\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-10\/","og_locale":"en_GB","og_type":"article","og_title":"19 Zoll Sommerr\u00e4der Sommerreifen 245\/45 Mercedes E Klasse All terrain S213 213 g\u00fcnstig kaufen - Felgenforum","og_description":"19 Zoll Sommerr\u00e4der Sommerreifen 245\/45 Mercedes E Klasse All terrain S213 213 online bestellen \u2794 Gepr\u00fcfte Qualit\u00e4t, Top Marken & schneller Versand \u2714 Jetzt sicher bei Felgenforum kaufen!","og_url":"https:\/\/felgenforum.shop\/en\/product\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-10\/","og_site_name":"Felgenforum","article_modified_time":"2026-04-25T13:25:04+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2026\/03\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-featured-1000px.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-10\/","url":"https:\/\/felgenforum.shop\/produkt\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-10\/","name":"19 Zoll Sommerr\u00e4der Sommerreifen 245\/45 Mercedes E Klasse All terrain S213 213 g\u00fcnstig kaufen - Felgenforum","isPartOf":{"@id":"https:\/\/felgenforum.shop\/#website"},"primaryImageOfPage":{"@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-10\/#primaryimage"},"image":{"@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-10\/#primaryimage"},"thumbnailUrl":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2026\/03\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-featured-1000px.webp","datePublished":"2026-03-04T23:38:22+00:00","dateModified":"2026-04-25T13:25:04+00:00","description":"19 Zoll Sommerr\u00e4der Sommerreifen 245\/45 Mercedes E Klasse All terrain S213 213 online bestellen \u2794 Gepr\u00fcfte Qualit\u00e4t, Top Marken & schneller Versand \u2714 Jetzt sicher bei Felgenforum kaufen!","breadcrumb":{"@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-10\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/felgenforum.shop\/produkt\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-10\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-10\/#primaryimage","url":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2026\/03\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-featured-1000px.webp","contentUrl":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2026\/03\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-featured-1000px.webp","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-sommerraeder-sommerreifen-245-45-mercedes-e-klasse-all-terrain-s213-213-10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/felgenforum.shop\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/felgenforum.shop\/shop\/"},{"@type":"ListItem","position":3,"name":"19 Zoll Sommerr\u00e4der Sommerreifen 245\/45 Mercedes E Klasse All terrain S213 213"}]},{"@type":"WebSite","@id":"https:\/\/felgenforum.shop\/#website","url":"https:\/\/felgenforum.shop\/","name":"Rim forum","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/felgenforum.shop\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product\/227170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/comments?post=227170"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/media\/227384"}],"wp:attachment":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/media?parent=227170"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_brand?post=227170"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_cat?post=227170"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_tag?post=227170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}