{"id":110556,"date":"2025-09-23T23:32:46","date_gmt":"2025-09-23T21:32:46","guid":{"rendered":"https:\/\/felgenforum.shop\/?post_type=product&#038;p=110556"},"modified":"2026-04-25T15:18:18","modified_gmt":"2026-04-25T13:18:18","slug":"ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg","status":"publish","type":"product","link":"https:\/\/felgenforum.shop\/en\/product\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg\/","title":{"rendered":"FF01 19 inch rims 4x summer wheels summer tires for Mercedes GLB class F2B AMG"},"content":{"rendered":"<h3>Welcome to an offer from Felgenforum.shop<\/h3>\n<p>In this offer we offer you a NEW set of summer complete wheels in matte grey including ABE.<\/p>\n<p>4x fully pre-assembled and balanced complete wheels<\/p>\n<p>consisting of:<\/p>\n<p>4x Alufelge FF-Wheels FF01 grau 8,5&#215;19 ET45 LK5\/112<\/p>\n<p>+<\/p>\n<p>4x summer tires 245\/45 R19 102Y from current daily purchase<\/p>\n<p>fully assembled and balanced<\/p>\n<p>+<\/p>\n<p>TPMS (pre-programmed)<\/p>\n<p>(including black weights and black metal valves)<\/p>\n<p>NEW<\/p>\n<h3>Scope of delivery:<\/h3>\n<ul>\n<li>4 x FF-Wheels FF01 8,5&#215;19 ET45 5&#215;112 grau matt<\/li>\n<li>Complete mounting hardware (if required according to the ABE)<\/li>\n<li>4x summer tires from current daily purchase 245\/45 R19 102Y<\/li>\n<li>4x TPMS (pre-programmed)<\/li>\n<li>4x Hubcaps FF-Wheels<\/li>\n<li>(Vehicle manufacturer&#039;s hubcap not included)<\/li>\n<li>1x Expert report (ABE)<\/li>\n<li>In most cases, the complete wheel sets are therefore registration-free. If you have any questions about fitment or any registration requirements, our experienced team will be happy to assist you :).<\/li>\n<li>Please be sure to specify your vehicle after purchase.<\/li>\n<li>We offer this model in many other sizes and colors; please contact us if you have any other requests.<\/li>\n<li>&gt;&gt;&gt;Wishful tires<\/li>\n<li>Do you have a specific request regarding tire brand or tire quality? No problem!<\/li>\n<li>We would be happy to create individual complete wheel offers for you :).<\/li>\n<li>The complete wheels are suitable for, among others:<\/li>\n<\/ul>\n<h3>Audi<\/h3>\n<ul>\n<li>A6 F2 C8<\/li>\n<\/ul>\n<h3>BMW<\/h3>\n<ul>\n<li>X1 U11<\/li>\n<li>IX1<\/li>\n<li>U11<\/li>\n<\/ul>\n<h3>Mercedes Benz<\/h3>\n<ul>\n<li>GLA F2B<\/li>\n<li>GLB F2B<\/li>\n<li>GLK 204X<\/li>\n<li>EQA<\/li>\n<li>EQB<\/li>\n<li>V Class W447 (axle load max 1500KG)<\/li>\n<li>Vito (maximum axle load 1500KG)<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>A set (4 pieces) of ready-to-drive FF Wheels complete wheels, professionally mounted and balanced.<\/p>\n<p><strong>Rim details:<\/strong> 8,5&#215;19 Zoll, Lochkreis 112.<br \/><strong>Tire details:<\/strong> Daily shopping. .<\/p>","protected":false},"featured_media":115497,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1471,1196,1470],"product_tag":[],"class_list":{"0":"post-110556","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-19-zoll-sommerraeder-mercedes-mercedes-komplettraeder-sommer","7":"product_cat-komplettraeder-sommer","8":"product_cat-mercedes-komplettraeder-sommer","9":"product_shipping_class-komplettrad","10":"pa_anzahl-der-komplettraeder-1433","11":"pa_einpresstiefe-et-1508","12":"pa_fahrzeugmarke-mercedes","13":"pa_felgenbreite-8-5","14":"pa_felgenfarbe-grau-matt","15":"pa_felgenhersteller-ff-wheels","16":"pa_felgenmaterial-aluminium","17":"pa_felgenmodell-ff01","18":"pa_geschwindigkeitsindex-y-bis-300-km-h","19":"pa_herstellernummer-felge-1696","20":"pa_lastbereich-xl","21":"pa_lochkreis-1439","22":"pa_lochzahl-1447","23":"pa_reifenbreite-1503","24":"pa_reifendurchmesser-1436","25":"pa_reifenhersteller-tageseinkauf","26":"pa_reifenquerschnitt-1504","27":"pa_reifenspezifikation-sommerreifen","28":"pa_run-flat-nein","29":"pa_tragfaehigkeitsindex-102-max-850-kg-je-reifen","30":"pa_zollgroesse-1448","32":"first","33":"instock","34":"sale","35":"taxable","36":"shipping-taxable","37":"purchasable","38":"product-type-simple"},"yoast_head":"<title>FF01 19 Zoll Felgen 4x Sommerr\u00e4der Sommerreifen f\u00fcr Mercedes GLB Klasse F2B AMG g\u00fcnstig kaufen - Felgenforum<\/title>\n<meta name=\"description\" content=\"FF01 19 Zoll Felgen 4x Sommerr\u00e4der Sommerreifen f\u00fcr Mercedes GLB Klasse F2B AMG online bestellen \u2794 Gepr\u00fcfte Qualit\u00e4t, Top Marken &amp; schneller Versand \u2714 Jetzt sicher bei Felgenforum kaufen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/felgenforum.shop\/en\/product\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FF01 19 Zoll Felgen 4x Sommerr\u00e4der Sommerreifen f\u00fcr Mercedes GLB Klasse F2B AMG g\u00fcnstig kaufen - Felgenforum\" \/>\n<meta property=\"og:description\" content=\"FF01 19 Zoll Felgen 4x Sommerr\u00e4der Sommerreifen f\u00fcr Mercedes GLB Klasse F2B AMG online bestellen \u2794 Gepr\u00fcfte Qualit\u00e4t, Top Marken &amp; schneller Versand \u2714 Jetzt sicher bei Felgenforum kaufen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/felgenforum.shop\/en\/product\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg\/\" \/>\n<meta property=\"og:site_name\" content=\"Felgenforum\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-25T13:18:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg-featured-1000px.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg\\\/\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg\\\/\",\"name\":\"FF01 19 Zoll Felgen 4x Sommerr\u00e4der Sommerreifen f\u00fcr Mercedes GLB Klasse F2B AMG g\u00fcnstig kaufen - Felgenforum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg-featured-1000px.webp\",\"datePublished\":\"2025-09-23T21:32:46+00:00\",\"dateModified\":\"2026-04-25T13:18:18+00:00\",\"description\":\"FF01 19 Zoll Felgen 4x Sommerr\u00e4der Sommerreifen f\u00fcr Mercedes GLB Klasse F2B AMG online bestellen \u2794 Gepr\u00fcfte Qualit\u00e4t, Top Marken & schneller Versand \u2714 Jetzt sicher bei Felgenforum kaufen!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg-featured-1000px.webp\",\"contentUrl\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg-featured-1000px.webp\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/felgenforum.shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/felgenforum.shop\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FF01 19 Zoll Felgen 4x Sommerr\u00e4der Sommerreifen f\u00fcr Mercedes GLB Klasse F2B AMG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/#website\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/\",\"name\":\"Felgenforum\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/felgenforum.shop\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>","yoast_head_json":{"title":"FF01 19 Zoll Felgen 4x Sommerr\u00e4der Sommerreifen f\u00fcr Mercedes GLB Klasse F2B AMG g\u00fcnstig kaufen - Felgenforum","description":"FF01 19 Zoll Felgen 4x Sommerr\u00e4der Sommerreifen f\u00fcr Mercedes GLB Klasse F2B AMG online bestellen \u2794 Gepr\u00fcfte Qualit\u00e4t, Top Marken & schneller Versand \u2714 Jetzt sicher bei Felgenforum kaufen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/felgenforum.shop\/en\/product\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg\/","og_locale":"en_GB","og_type":"article","og_title":"FF01 19 Zoll Felgen 4x Sommerr\u00e4der Sommerreifen f\u00fcr Mercedes GLB Klasse F2B AMG g\u00fcnstig kaufen - Felgenforum","og_description":"FF01 19 Zoll Felgen 4x Sommerr\u00e4der Sommerreifen f\u00fcr Mercedes GLB Klasse F2B AMG online bestellen \u2794 Gepr\u00fcfte Qualit\u00e4t, Top Marken & schneller Versand \u2714 Jetzt sicher bei Felgenforum kaufen!","og_url":"https:\/\/felgenforum.shop\/en\/product\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg\/","og_site_name":"Felgenforum","article_modified_time":"2026-04-25T13:18:18+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg-featured-1000px.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/felgenforum.shop\/produkt\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg\/","url":"https:\/\/felgenforum.shop\/produkt\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg\/","name":"FF01 19 Zoll Felgen 4x Sommerr\u00e4der Sommerreifen f\u00fcr Mercedes GLB Klasse F2B AMG g\u00fcnstig kaufen - Felgenforum","isPartOf":{"@id":"https:\/\/felgenforum.shop\/#website"},"primaryImageOfPage":{"@id":"https:\/\/felgenforum.shop\/produkt\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg\/#primaryimage"},"image":{"@id":"https:\/\/felgenforum.shop\/produkt\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg\/#primaryimage"},"thumbnailUrl":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg-featured-1000px.webp","datePublished":"2025-09-23T21:32:46+00:00","dateModified":"2026-04-25T13:18:18+00:00","description":"FF01 19 Zoll Felgen 4x Sommerr\u00e4der Sommerreifen f\u00fcr Mercedes GLB Klasse F2B AMG online bestellen \u2794 Gepr\u00fcfte Qualit\u00e4t, Top Marken & schneller Versand \u2714 Jetzt sicher bei Felgenforum kaufen!","breadcrumb":{"@id":"https:\/\/felgenforum.shop\/produkt\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/felgenforum.shop\/produkt\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/felgenforum.shop\/produkt\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg\/#primaryimage","url":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg-featured-1000px.webp","contentUrl":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg-featured-1000px.webp","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/felgenforum.shop\/produkt\/ff01-19-zoll-felgen-4x-sommerraeder-sommerreifen-fuer-mercedes-glb-klasse-f2b-amg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/felgenforum.shop\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/felgenforum.shop\/shop\/"},{"@type":"ListItem","position":3,"name":"FF01 19 Zoll Felgen 4x Sommerr\u00e4der Sommerreifen f\u00fcr Mercedes GLB Klasse F2B AMG"}]},{"@type":"WebSite","@id":"https:\/\/felgenforum.shop\/#website","url":"https:\/\/felgenforum.shop\/","name":"Rim forum","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/felgenforum.shop\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product\/110556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/comments?post=110556"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/media\/115497"}],"wp:attachment":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/media?parent=110556"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_brand?post=110556"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_cat?post=110556"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_tag?post=110556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}