{"id":106291,"date":"2025-09-23T08:52:44","date_gmt":"2025-09-23T06:52:44","guid":{"rendered":"https:\/\/felgenforum.shop\/?post_type=product&#038;p=106291"},"modified":"2026-04-25T15:16:20","modified_gmt":"2026-04-25T13:16:20","slug":"19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209","status":"publish","type":"product","link":"https:\/\/felgenforum.shop\/en\/product\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209\/","title":{"rendered":"19-inch RS4 black rims for Mercedes CLS W218 W219 CLK W208 W209"},"content":{"rendered":"<h3>Welcome to an offer from Felgenforum.shop<\/h3>\n<p>In this offer we offer you a NEW set of MAM RS4 alloy wheels in black including ABE (German type approval).<\/p>\n<p>NEW &amp; in original packaging.<\/p>\n<h3>Scope of delivery:<\/h3>\n<ul>\n<li>4 x\u00a0MAM RS4\u00a08,5&#215;19 ET30 5&#215;112\u00a0schwarz\u00a0<\/li>\n<li>Complete mounting hardware (if required according to the ABE)<\/li>\n<li>4x MAM hubcaps<\/li>\n<li>1x Expert report (ABE)<\/li>\n<li>In most cases, the rims are therefore registration-free. If you have any questions about fitment or any registration requirements, our experienced team will be happy to help :).<\/li>\n<li>Please be sure to specify your vehicle after purchase.<\/li>\n<li>We offer this model in many other sizes and colors; please contact us if you have any other requests.<\/li>\n<\/ul>\n<h3>&gt;&gt;&gt;Complete wheels<\/h3>\n<h3>We are happy to offer you the desired rims as ready-to-install complete wheels with a tire of your choice.<\/h3>\n<p>Feel free to send us a non-binding inquiry :).<\/p>\n<p>The rims are the correct size for the following vehicles:<\/p>\n<h3>Audi<\/h3>\n<ul>\n<li>A4 S4 B8 B9 B81<\/li>\n<li>A5 B8 B9 S5<\/li>\n<li>A6 S6 4G 4G1 C7 F2 C8<\/li>\n<li>A7 4G 4G1 F2 S7<\/li>\n<li>A8 4H F8 S8<\/li>\n<li>Q3 F3<\/li>\n<li>Q5 8R FY SQ5<\/li>\n<\/ul>\n<h3>Volkswagen<\/h3>\n<ul>\n<li>Arteon 3H<\/li>\n<li>Passat CC<\/li>\n<li>Sirocco\u00a0<\/li>\n<li>Phaeton 3D<\/li>\n<li>Tiguan 5N1 5N2<\/li>\n<\/ul>\n<h3>Mercedes Benz<\/h3>\n<ul>\n<li>C-Class W203\u00a0<\/li>\n<li>CLK W208 W209<\/li>\n<li>E-Class W211 W213 W212 W217<\/li>\n<li>CL Class C216<\/li>\n<li>CLS Class W218 W219<\/li>\n<li>CLK Class W208 W209<\/li>\n<li>GLC W253 X253<\/li>\n<li>S-Class W220 W221 W222<\/li>\n<li>SL R230 R231<\/li>\n<li>SLK SLC R172 R171<\/li>\n<li>Seat<\/li>\n<li>Alahambra<\/li>\n<li>Ateca \/ Cupra<\/li>\n<li>Formentor \/ Cupra<\/li>\n<li>Tarraco<\/li>\n<\/ul>\n<h3>Skoda<\/h3>\n<ul>\n<li>Kodiaq<\/li>\n<li>Superb 3 4 3T<\/li>\n<\/ul>\n<h3>BMW<\/h3>\n<ul>\n<li>3 Series G20 G21 G3C G3K<\/li>\n<li>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a04er G22 G23 G26<\/li>\n<li>5 Series G30 G31<\/li>\n<li>6er G6GT G32<\/li>\n<li>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 7-series 7L<\/li>\n<li>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Z4 G4Z<\/li>\n<li>X3 G01<\/li>\n<li>X4 G02<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>A set (4 pieces) of high-quality brand-name alloy wheels, model RS4, size 8.5Jx19 inches, bolt pattern 112 with 5 holes. Professionally inspected and packaged ready for shipping.<\/p>","protected":false},"featured_media":110414,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1180,1086,1179],"product_tag":[],"class_list":{"0":"post-106291","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-19-zoll","7":"product_cat-felgen","8":"product_cat-mercedes","9":"product_shipping_class-felge","10":"pa_anzahl-der-einheiten-1484","11":"pa_einpresstiefe-et-1450","12":"pa_fahrzeugmarke-mercedes","13":"pa_farbe-schwarz","14":"pa_felgenaufbau-einteilig-gegossen","15":"pa_felgenbreite-8-5","16":"pa_felgendesign-multi-speichen-felge","17":"pa_felgenfarbe-schwarz","18":"pa_felgenmaterial-aluminium","19":"pa_felgenmodell-rs4","20":"pa_hersteller-mam","21":"pa_herstellergarantie-ja-zwei-jahre","22":"pa_herstellernummer-mamrs48519511230bp","23":"pa_herstellungsland-und-regi-deutschland","24":"pa_lochkreis-1439","25":"pa_lochzahl-1447","26":"pa_maximale-traglast-2037","27":"pa_mit-deckel-ja-nein-ja-von-damina","28":"pa_mittenlochbohrung-1551","29":"pa_modell-rs4","30":"pa_produktart-vielspeiche","31":"pa_zollgroesse-1448","33":"first","34":"instock","35":"taxable","36":"shipping-taxable","37":"purchasable","38":"product-type-simple"},"yoast_head":"<title>19 Zoll Felgen RS4 schwarz f\u00fcr Mercedes CLS W218 W219 CLK W208 W209 g\u00fcnstig kaufen - Felgenforum<\/title>\n<meta name=\"description\" content=\"Versch\u00f6nern Sie Ihren Mercedes mit 19 Zoll Felgen RS4 schwarz. Sportliches Design und perfekte Passform f\u00fcr CLS und CLK. Jetzt entdecken und kaufen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/felgenforum.shop\/en\/product\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"19 Zoll Felgen RS4 schwarz f\u00fcr Mercedes CLS W218 W219 CLK W208 W209 g\u00fcnstig kaufen - Felgenforum\" \/>\n<meta property=\"og:description\" content=\"Versch\u00f6nern Sie Ihren Mercedes mit 19 Zoll Felgen RS4 schwarz. Sportliches Design und perfekte Passform f\u00fcr CLS und CLK. Jetzt entdecken und kaufen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/felgenforum.shop\/en\/product\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209\/\" \/>\n<meta property=\"og:site_name\" content=\"Felgenforum\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-25T13:16:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209-featured-1000px.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209\\\/\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209\\\/\",\"name\":\"19 Zoll Felgen RS4 schwarz f\u00fcr Mercedes CLS W218 W219 CLK W208 W209 g\u00fcnstig kaufen - Felgenforum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209-featured-1000px.webp\",\"datePublished\":\"2025-09-23T06:52:44+00:00\",\"dateModified\":\"2026-04-25T13:16:20+00:00\",\"description\":\"Versch\u00f6nern Sie Ihren Mercedes mit 19 Zoll Felgen RS4 schwarz. Sportliches Design und perfekte Passform f\u00fcr CLS und CLK. Jetzt entdecken und kaufen!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209\\\/#primaryimage\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209-featured-1000px.webp\",\"contentUrl\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209-featured-1000px.webp\",\"width\":1000,\"height\":1000,\"caption\":\"Schwarze 19 Zoll RS4 Felgen passend f\u00fcr Mercedes CLS und CLK\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/felgenforum.shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/felgenforum.shop\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"19 Zoll Felgen RS4 schwarz f\u00fcr Mercedes CLS W218 W219 CLK W208 W209\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/#website\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/\",\"name\":\"Felgenforum\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/felgenforum.shop\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>","yoast_head_json":{"title":"19 Zoll Felgen RS4 schwarz f\u00fcr Mercedes CLS W218 W219 CLK W208 W209 g\u00fcnstig kaufen - Felgenforum","description":"Versch\u00f6nern Sie Ihren Mercedes mit 19 Zoll Felgen RS4 schwarz. Sportliches Design und perfekte Passform f\u00fcr CLS und CLK. Jetzt entdecken und kaufen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/felgenforum.shop\/en\/product\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209\/","og_locale":"en_GB","og_type":"article","og_title":"19 Zoll Felgen RS4 schwarz f\u00fcr Mercedes CLS W218 W219 CLK W208 W209 g\u00fcnstig kaufen - Felgenforum","og_description":"Versch\u00f6nern Sie Ihren Mercedes mit 19 Zoll Felgen RS4 schwarz. Sportliches Design und perfekte Passform f\u00fcr CLS und CLK. Jetzt entdecken und kaufen!","og_url":"https:\/\/felgenforum.shop\/en\/product\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209\/","og_site_name":"Felgenforum","article_modified_time":"2026-04-25T13:16:20+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209-featured-1000px.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209\/","url":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209\/","name":"19 Zoll Felgen RS4 schwarz f\u00fcr Mercedes CLS W218 W219 CLK W208 W209 g\u00fcnstig kaufen - Felgenforum","isPartOf":{"@id":"https:\/\/felgenforum.shop\/#website"},"primaryImageOfPage":{"@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209\/#primaryimage"},"image":{"@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209\/#primaryimage"},"thumbnailUrl":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209-featured-1000px.webp","datePublished":"2025-09-23T06:52:44+00:00","dateModified":"2026-04-25T13:16:20+00:00","description":"Versch\u00f6nern Sie Ihren Mercedes mit 19 Zoll Felgen RS4 schwarz. Sportliches Design und perfekte Passform f\u00fcr CLS und CLK. Jetzt entdecken und kaufen!","breadcrumb":{"@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209\/#primaryimage","url":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209-featured-1000px.webp","contentUrl":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209-featured-1000px.webp","width":1000,"height":1000,"caption":"Schwarze 19 Zoll RS4 Felgen passend f\u00fcr Mercedes CLS und CLK"},{"@type":"BreadcrumbList","@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-rs4-schwarz-fuer-mercedes-cls-w218-w219-clk-w208-w209\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/felgenforum.shop\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/felgenforum.shop\/shop\/"},{"@type":"ListItem","position":3,"name":"19 Zoll Felgen RS4 schwarz f\u00fcr Mercedes CLS W218 W219 CLK W208 W209"}]},{"@type":"WebSite","@id":"https:\/\/felgenforum.shop\/#website","url":"https:\/\/felgenforum.shop\/","name":"Rim forum","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/felgenforum.shop\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product\/106291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/comments?post=106291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/media\/110414"}],"wp:attachment":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/media?parent=106291"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_brand?post=106291"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_cat?post=106291"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_tag?post=106291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}