{"id":106099,"date":"2025-09-23T08:13:12","date_gmt":"2025-09-23T06:13:12","guid":{"rendered":"https:\/\/felgenforum.shop\/?post_type=product&#038;p=106099"},"modified":"2026-04-25T15:16:16","modified_gmt":"2026-04-25T13:16:16","slug":"19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222","status":"publish","type":"product","link":"https:\/\/felgenforum.shop\/en\/product\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222\/","title":{"rendered":"19-inch Damina DM08 grey rims for Mercedes E-Class, GLC, and S-Class W211, W213, W221, and W222"},"content":{"rendered":"<h3>Welcome to an offer from Felgenforum.shop<\/h3>\n<p>In this offer we offer you a NEW set of Damina Performance DM08 alloy wheels in matte grey including ABE.<\/p>\n<p>NEW &amp; in original packaging.<\/p>\n<h3>Scope of delivery:<\/h3>\n<ul>\n<li>4 x Damina DM08 8,5&#215;19 ET35 5&#215;112 grau matt<\/li>\n<li>Complete mounting hardware (if required according to the ABE)<\/li>\n<li>4x hub caps Damina Performance ()<\/li>\n<li>1x Expert report (ABE)<\/li>\n<li>In most cases, the rims are therefore registration-free. If you have any questions about fitment or any registration requirements, our experienced team will be happy to help :).<\/li>\n<li>Please be sure to specify your vehicle after purchase.<\/li>\n<li>We offer this model in many other sizes and colors; please contact us if you have any other requests.<\/li>\n<\/ul>\n<h3>&gt;&gt;&gt;Complete wheels<\/h3>\n<h3>We are happy to offer you the desired rims as ready-to-install complete wheels with a tire of your choice.<\/h3>\n<p>Feel free to send us a non-binding inquiry :).<\/p>\n<p>The rims are the correct size for the following vehicles:<\/p>\n<h3>Audi<\/h3>\n<ul>\n<li>A4 S4 B8 B81<\/li>\n<li>A5 B8 B9<\/li>\n<li>A6 S6 4F 4F1 C6 4G 4G1 C7 F2 C8<\/li>\n<li>A7 4G 4G1<\/li>\n<li>A8 4E<\/li>\n<li>TT TTS TTRS 8J 8S FV<\/li>\n<li>Q2 SQ2 GA<\/li>\n<li>Q3 8U 8U1<\/li>\n<li>Q5 8R FY<\/li>\n<\/ul>\n<h3>Volkswagen<\/h3>\n<ul>\n<li>Beetle 2<\/li>\n<li>Arteon 3H<\/li>\n<li>Passat B8<\/li>\n<li>Passat CC<\/li>\n<li>Sirocco<\/li>\n<li>Phaeton 3D<\/li>\n<li>Tiguan 5N1 5N2<\/li>\n<\/ul>\n<h3>Mercedes Benz<\/h3>\n<ul>\n<li>C-Class W203<\/li>\n<li>CLK W208 W209<\/li>\n<li>E-Class W211 W213<\/li>\n<li>CL Class C215 C216<\/li>\n<li>S-Class W221 W222<\/li>\n<li>SL R230 R231<\/li>\n<li>SLK SLC R172<\/li>\n<li>Seat<\/li>\n<li>Tarraco<\/li>\n<\/ul>\n<h3>Skoda<\/h3>\n<ul>\n<li>Kodiaq<\/li>\n<li>Superb 3 4 3T<\/li>\n<\/ul>\n<h3>BMW<\/h3>\n<ul>\n<li>X3 G01<\/li>\n<li>X4 G02<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>A set (4 pieces) of high-quality brand-name alloy wheels, model DM08, size 8.5Jx19 inches, bolt pattern 112 with 5 holes. Professionally inspected and packaged ready for shipping.<\/p>","protected":false},"featured_media":110063,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1180,1086,1179],"product_tag":[],"class_list":{"0":"post-106099","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-19-zoll","7":"product_cat-felgen","8":"product_cat-mercedes","9":"product_shipping_class-felge","10":"pa_anzahl-der-einheiten-1484","11":"pa_einpresstiefe-et-1460","12":"pa_fahrzeugmarke-mercedes","13":"pa_farbe-grau","14":"pa_felgenaufbau-einteilig-gegossen","15":"pa_felgenbreite-8-5","16":"pa_felgendesign-multi-speichen-felge","17":"pa_felgenfarbe-grau","18":"pa_felgenmaterial-aluminium","19":"pa_felgenmodell-dm08","20":"pa_hersteller-damina-performance","21":"pa_herstellergarantie-ja-zwei-jahre","22":"pa_herstellernummer-1955","23":"pa_herstellungsland-und-regi-deutschland","24":"pa_lochkreis-1439","25":"pa_lochzahl-1447","26":"pa_maximale-traglast-1498","27":"pa_mit-deckel-ja-nein-ja-von-damina","28":"pa_mittenlochbohrung-1551","29":"pa_modell-dm08","30":"pa_produktart-vielspeiche","31":"pa_zollgroesse-1448","33":"first","34":"instock","35":"taxable","36":"shipping-taxable","37":"purchasable","38":"product-type-simple"},"yoast_head":"<title>19 Zoll Felgen Damina DM08 grau Mercedes E GLC S Klasse W211 W213 W221 W222 g\u00fcnstig kaufen - Felgenforum<\/title>\n<meta name=\"description\" content=\"Verleihen Sie Ihrem Mercedes mit 19 Zoll Felgen Damina DM08 in Grau einen sportlichen Look. Passgenau f\u00fcr E, GLC und S-Klasse. Jetzt online kaufen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/felgenforum.shop\/en\/product\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"19 Zoll Felgen Damina DM08 grau Mercedes E GLC S Klasse W211 W213 W221 W222 g\u00fcnstig kaufen - Felgenforum\" \/>\n<meta property=\"og:description\" content=\"Verleihen Sie Ihrem Mercedes mit 19 Zoll Felgen Damina DM08 in Grau einen sportlichen Look. Passgenau f\u00fcr E, GLC und S-Klasse. Jetzt online kaufen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/felgenforum.shop\/en\/product\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222\/\" \/>\n<meta property=\"og:site_name\" content=\"Felgenforum\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-25T13:16:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222-featured-1000px.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222\\\/\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222\\\/\",\"name\":\"19 Zoll Felgen Damina DM08 grau Mercedes E GLC S Klasse W211 W213 W221 W222 g\u00fcnstig kaufen - Felgenforum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222-featured-1000px.webp\",\"datePublished\":\"2025-09-23T06:13:12+00:00\",\"dateModified\":\"2026-04-25T13:16:16+00:00\",\"description\":\"Verleihen Sie Ihrem Mercedes mit 19 Zoll Felgen Damina DM08 in Grau einen sportlichen Look. Passgenau f\u00fcr E, GLC und S-Klasse. Jetzt online kaufen!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222\\\/#primaryimage\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222-featured-1000px.webp\",\"contentUrl\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222-featured-1000px.webp\",\"width\":1000,\"height\":1000,\"caption\":\"Sportliche 19 Zoll Felgen Damina DM08 grau passend f\u00fcr Mercedes Benz\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/felgenforum.shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/felgenforum.shop\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"19 Zoll Felgen Damina DM08 grau Mercedes E GLC S Klasse W211 W213 W221 W222\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/#website\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/\",\"name\":\"Felgenforum\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/felgenforum.shop\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>","yoast_head_json":{"title":"19 Zoll Felgen Damina DM08 grau Mercedes E GLC S Klasse W211 W213 W221 W222 g\u00fcnstig kaufen - Felgenforum","description":"Verleihen Sie Ihrem Mercedes mit 19 Zoll Felgen Damina DM08 in Grau einen sportlichen Look. Passgenau f\u00fcr E, GLC und S-Klasse. Jetzt online kaufen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/felgenforum.shop\/en\/product\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222\/","og_locale":"en_GB","og_type":"article","og_title":"19 Zoll Felgen Damina DM08 grau Mercedes E GLC S Klasse W211 W213 W221 W222 g\u00fcnstig kaufen - Felgenforum","og_description":"Verleihen Sie Ihrem Mercedes mit 19 Zoll Felgen Damina DM08 in Grau einen sportlichen Look. Passgenau f\u00fcr E, GLC und S-Klasse. Jetzt online kaufen!","og_url":"https:\/\/felgenforum.shop\/en\/product\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222\/","og_site_name":"Felgenforum","article_modified_time":"2026-04-25T13:16:16+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222-featured-1000px.webp","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222\/","url":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222\/","name":"19 Zoll Felgen Damina DM08 grau Mercedes E GLC S Klasse W211 W213 W221 W222 g\u00fcnstig kaufen - Felgenforum","isPartOf":{"@id":"https:\/\/felgenforum.shop\/#website"},"primaryImageOfPage":{"@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222\/#primaryimage"},"image":{"@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222\/#primaryimage"},"thumbnailUrl":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222-featured-1000px.webp","datePublished":"2025-09-23T06:13:12+00:00","dateModified":"2026-04-25T13:16:16+00:00","description":"Verleihen Sie Ihrem Mercedes mit 19 Zoll Felgen Damina DM08 in Grau einen sportlichen Look. Passgenau f\u00fcr E, GLC und S-Klasse. Jetzt online kaufen!","breadcrumb":{"@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222\/#primaryimage","url":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222-featured-1000px.webp","contentUrl":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222-featured-1000px.webp","width":1000,"height":1000,"caption":"Sportliche 19 Zoll Felgen Damina DM08 grau passend f\u00fcr Mercedes Benz"},{"@type":"BreadcrumbList","@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-damina-dm08-grau-mercedes-e-glc-s-klasse-w211-w213-w221-w222\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/felgenforum.shop\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/felgenforum.shop\/shop\/"},{"@type":"ListItem","position":3,"name":"19 Zoll Felgen Damina DM08 grau Mercedes E GLC S Klasse W211 W213 W221 W222"}]},{"@type":"WebSite","@id":"https:\/\/felgenforum.shop\/#website","url":"https:\/\/felgenforum.shop\/","name":"Rim forum","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/felgenforum.shop\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product\/106099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/comments?post=106099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/media\/110063"}],"wp:attachment":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/media?parent=106099"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_brand?post=106099"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_cat?post=106099"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_tag?post=106099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}