{"id":105808,"date":"2025-09-23T07:12:41","date_gmt":"2025-09-23T05:12:41","guid":{"rendered":"https:\/\/felgenforum.shop\/?post_type=product&#038;p=105808"},"modified":"2026-04-25T15:16:08","modified_gmt":"2026-04-25T13:16:08","slug":"20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-2","status":"publish","type":"product","link":"https:\/\/felgenforum.shop\/en\/product\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-2\/","title":{"rendered":"20-inch FF Wheels FF01 Grey rims for Mercedes CE Class W204 W205 W212 W213"},"content":{"rendered":"<h3>Welcome to an offer from Felgenforum.shop<\/h3>\n<p>In this offer we offer you a NEW set of FF Wheels FF01 alloy wheels in matte grey including ABE.<\/p>\n<p>NEW &amp; in original packaging.<\/p>\n<h3>Scope of delivery:<\/h3>\n<ul>\n<li>4 x FF Wheels FF01 8,5&#215;20 ET45 5&#215;112 grau matt<\/li>\n<li>Complete mounting hardware (if required according to the ABE)<\/li>\n<li>4x Hubcaps FF Wheels<\/li>\n<li>(Vehicle manufacturer&#039;s hubcap not included)<\/li>\n<li>1x Expert report (ABE)<\/li>\n<li>In most cases, the rims are therefore registration-free. If you have any questions about fitment or any registration requirements, our experienced team will be happy to help :).<\/li>\n<li>Please be sure to specify your vehicle after purchase.<\/li>\n<li>We offer this model in many other sizes and colors; please contact us if you have any other requests.<\/li>\n<\/ul>\n<h3>&gt;&gt;&gt;Complete wheels<\/h3>\n<h3>We are happy to offer you the desired rims as ready-to-install complete wheels with a tire of your choice.<\/h3>\n<p>Feel free to send us a non-binding inquiry :).<\/p>\n<p>The rims are the correct size for the following vehicles:<\/p>\n<h3>Audi<\/h3>\n<ul>\n<li>A3 S3 8V GY\u00a0<\/li>\n<li>A4 S4 B8 B81<\/li>\n<li>A6 S6 4F 4F1 C6 4G 4G1 C7 F2 C8<\/li>\n<li>A8 4E<\/li>\n<li>TT TTS TTRS 8J 8S FV<\/li>\n<li>Q2 SQ2 GA<\/li>\n<li>Q3 8U 8U1<\/li>\n<\/ul>\n<h3>Volkswagen<\/h3>\n<ul>\n<li>Golf 7 8 in all versions<\/li>\n<li>ID.3<\/li>\n<li>ID.4<\/li>\n<li>ID.5<\/li>\n<li>ID.7<\/li>\n<li>Passat B6 B7 B8 B9<\/li>\n<li>Phaeton 3D<\/li>\n<li>Tiguan 5N1<\/li>\n<li>T-ROC A1<\/li>\n<\/ul>\n<h3>Mercedes Benz<\/h3>\n<ul>\n<li>A-Class W176 W177<\/li>\n<li>B Class W246 W247<\/li>\n<li>C-Class W204 W205 all body styles<\/li>\n<li>CLA Class C117 C118<\/li>\n<li>E-Class W212 W213 (not T-Model)<\/li>\n<li>CL Class C215<\/li>\n<li>EQA250 F2B<\/li>\n<li>GLA 245G F2B<\/li>\n<li>GLB F2B<\/li>\n<li>GLK X204<\/li>\n<li>S-Class W220<\/li>\n<li>Vito 639 W447<\/li>\n<li>V Class W447<\/li>\n<li>Seat<\/li>\n<li>Ateca 5FP also Cupra<\/li>\n<li>Leon 5F KL also Cupra<\/li>\n<\/ul>\n<h3>Skoda<\/h3>\n<ul>\n<li>Octavia 5E NX<\/li>\n<li>Superb 3 4 3T<\/li>\n<li>Yeti 5L<\/li>\n<li>Karoq NU<\/li>\n<li>Enyaq 50 60 80 85 RS X<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Ein Satz (4 St\u00fcck) hochwertige Marken-Alufelgen, Modell FF01, in der Gr\u00f6\u00dfe 8,5&#215;20 Zoll, Lochkreis 112 mit 5 Loch. Professionell gepr\u00fcft und versandfertig verpackt.<\/p>","protected":false},"featured_media":109532,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1344,1086,1179],"product_tag":[],"class_list":{"0":"post-105808","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-20-zoll","7":"product_cat-felgen","8":"product_cat-mercedes","9":"product_shipping_class-felge","10":"pa_anzahl-der-einheiten-1484","11":"pa_einpresstiefe-et-1508","12":"pa_fahrzeugmarke-mercedes","13":"pa_farbe-grau-matt","14":"pa_felgenaufbau-einteilig-gegossen","15":"pa_felgenbreite-8-5","16":"pa_felgendesign-multi-speichen-felge","17":"pa_felgenfarbe-grau","18":"pa_felgenmaterial-aluminium","19":"pa_felgenmodell-ff01","20":"pa_hersteller-ff-wheels","21":"pa_herstellergarantie-ja-zwei-jahre","22":"pa_herstellernummer-2155","23":"pa_herstellungsland-und-regi-deutschland","24":"pa_lochkreis-1439","25":"pa_lochzahl-1447","26":"pa_maximale-traglast-750-kg","27":"pa_mit-deckel-ja-nein-ja-von-damina","28":"pa_mittenlochbohrung-666-mm","29":"pa_modell-ff01","30":"pa_produktart-kreuzspeiche","31":"pa_zollgroesse-1499","33":"first","34":"instock","35":"taxable","36":"shipping-taxable","37":"purchasable","38":"product-type-simple"},"yoast_head":"<title>20 Zoll Felgen FF Wheels FF01 Grau f\u00fcr Mercedes C E Klasse W204 W205 W212 W213 g\u00fcnstig kaufen - Felgenforum<\/title>\n<meta name=\"description\" content=\"Werten Sie Ihren Mercedes mit 20 Zoll FF Wheels FF01 Felgen in Grau auf. Perfekte Passform f\u00fcr W204 bis W213. Jetzt online entdecken!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/felgenforum.shop\/en\/product\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"20 Zoll Felgen FF Wheels FF01 Grau f\u00fcr Mercedes C E Klasse W204 W205 W212 W213 g\u00fcnstig kaufen - Felgenforum\" \/>\n<meta property=\"og:description\" content=\"Werten Sie Ihren Mercedes mit 20 Zoll FF Wheels FF01 Felgen in Grau auf. Perfekte Passform f\u00fcr W204 bis W213. Jetzt online entdecken!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/felgenforum.shop\/en\/product\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Felgenforum\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-25T13:16:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-featured-1000px-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-2\\\/\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-2\\\/\",\"name\":\"20 Zoll Felgen FF Wheels FF01 Grau f\u00fcr Mercedes C E Klasse W204 W205 W212 W213 g\u00fcnstig kaufen - Felgenforum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-featured-1000px-1.webp\",\"datePublished\":\"2025-09-23T05:12:41+00:00\",\"dateModified\":\"2026-04-25T13:16:08+00:00\",\"description\":\"Werten Sie Ihren Mercedes mit 20 Zoll FF Wheels FF01 Felgen in Grau auf. Perfekte Passform f\u00fcr W204 bis W213. Jetzt online entdecken!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-2\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-featured-1000px-1.webp\",\"contentUrl\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-featured-1000px-1.webp\",\"width\":1000,\"height\":1000,\"caption\":\"Hochwertige 20 Zoll FF Wheels FF01 Felgen Grau f\u00fcr Mercedes Fahrzeuge\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/felgenforum.shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/felgenforum.shop\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"20 Zoll Felgen FF Wheels FF01 Grau f\u00fcr Mercedes C E Klasse W204 W205 W212 W213\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/#website\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/\",\"name\":\"Felgenforum\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/felgenforum.shop\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>","yoast_head_json":{"title":"20 Zoll Felgen FF Wheels FF01 Grau f\u00fcr Mercedes C E Klasse W204 W205 W212 W213 g\u00fcnstig kaufen - Felgenforum","description":"Werten Sie Ihren Mercedes mit 20 Zoll FF Wheels FF01 Felgen in Grau auf. Perfekte Passform f\u00fcr W204 bis W213. Jetzt online entdecken!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/felgenforum.shop\/en\/product\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-2\/","og_locale":"en_GB","og_type":"article","og_title":"20 Zoll Felgen FF Wheels FF01 Grau f\u00fcr Mercedes C E Klasse W204 W205 W212 W213 g\u00fcnstig kaufen - Felgenforum","og_description":"Werten Sie Ihren Mercedes mit 20 Zoll FF Wheels FF01 Felgen in Grau auf. Perfekte Passform f\u00fcr W204 bis W213. Jetzt online entdecken!","og_url":"https:\/\/felgenforum.shop\/en\/product\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-2\/","og_site_name":"Felgenforum","article_modified_time":"2026-04-25T13:16:08+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-featured-1000px-1.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/felgenforum.shop\/produkt\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-2\/","url":"https:\/\/felgenforum.shop\/produkt\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-2\/","name":"20 Zoll Felgen FF Wheels FF01 Grau f\u00fcr Mercedes C E Klasse W204 W205 W212 W213 g\u00fcnstig kaufen - Felgenforum","isPartOf":{"@id":"https:\/\/felgenforum.shop\/#website"},"primaryImageOfPage":{"@id":"https:\/\/felgenforum.shop\/produkt\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-2\/#primaryimage"},"image":{"@id":"https:\/\/felgenforum.shop\/produkt\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-2\/#primaryimage"},"thumbnailUrl":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-featured-1000px-1.webp","datePublished":"2025-09-23T05:12:41+00:00","dateModified":"2026-04-25T13:16:08+00:00","description":"Werten Sie Ihren Mercedes mit 20 Zoll FF Wheels FF01 Felgen in Grau auf. Perfekte Passform f\u00fcr W204 bis W213. Jetzt online entdecken!","breadcrumb":{"@id":"https:\/\/felgenforum.shop\/produkt\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-2\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/felgenforum.shop\/produkt\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/felgenforum.shop\/produkt\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-2\/#primaryimage","url":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-featured-1000px-1.webp","contentUrl":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-featured-1000px-1.webp","width":1000,"height":1000,"caption":"Hochwertige 20 Zoll FF Wheels FF01 Felgen Grau f\u00fcr Mercedes Fahrzeuge"},{"@type":"BreadcrumbList","@id":"https:\/\/felgenforum.shop\/produkt\/20-zoll-felgen-ff-wheels-ff01-grau-fuer-mercedes-c-e-klasse-w204-w205-w212-w213-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/felgenforum.shop\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/felgenforum.shop\/shop\/"},{"@type":"ListItem","position":3,"name":"20 Zoll Felgen FF Wheels FF01 Grau f\u00fcr Mercedes C E Klasse W204 W205 W212 W213"}]},{"@type":"WebSite","@id":"https:\/\/felgenforum.shop\/#website","url":"https:\/\/felgenforum.shop\/","name":"Rim forum","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/felgenforum.shop\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product\/105808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/comments?post=105808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/media\/109532"}],"wp:attachment":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/media?parent=105808"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_brand?post=105808"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_cat?post=105808"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_tag?post=105808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}