{"id":102184,"date":"2025-09-22T18:18:56","date_gmt":"2025-09-22T16:18:56","guid":{"rendered":"https:\/\/felgenforum.shop\/?post_type=product&#038;p=102184"},"modified":"2026-04-25T15:14:23","modified_gmt":"2026-04-25T13:14:23","slug":"19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8","status":"publish","type":"product","link":"https:\/\/felgenforum.shop\/en\/product\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8\/","title":{"rendered":"19-inch KT15 black rims for VW Golf 6 7 8 GTI GTD GTE 7R 8R Passat B6 B7 B8"},"content":{"rendered":"<h3>Welcome to an offer from Felgenforum.shop<\/h3>\n<p>In this offer we offer you a NEW set of Keskin KT15 alloy wheels in glossy black with polished horns, including ABE certification.<\/p>\n<p>NEW &amp; in original packaging.<\/p>\n<h3>Scope of delivery:<\/h3>\n<ul>\n<li>4 x Keskin KT15 8,5&#215;19 ET45 5&#215;112 schwarz gl\u00e4nzend hornpoliert<\/li>\n<li>Complete mounting hardware (if required according to the ABE)<\/li>\n<li>4x Keskin hubcaps<\/li>\n<li>(Vehicle manufacturer&#039;s hubcap not included)<\/li>\n<li>1x Expert report (ABE)<\/li>\n<li>In most cases, the rims are therefore registration-free. If you have any questions about fitment or any registration requirements, our experienced team will be happy to help :).<\/li>\n<li>Please be sure to specify your vehicle after purchase.<\/li>\n<li>We offer this model in many other sizes and colors; please contact us if you have any other requests.<\/li>\n<\/ul>\n<h3>&gt;&gt;&gt;Complete wheels<\/h3>\n<h3>We are happy to offer you the desired rims as ready-to-install complete wheels with a tire of your choice.<\/h3>\n<p>Feel free to send us a non-binding inquiry :).<\/p>\n<p>The rims are the correct size for the following vehicles:<\/p>\n<h3>Audi<\/h3>\n<ul>\n<li>A3 S3 8P 8P1 8V GY\u00a0<\/li>\n<li>A4 S4 B8 B81<\/li>\n<li>A6 S6 4F 4F1 C6 4G 4G1 C7 F2 C8<\/li>\n<li>A8 4E<\/li>\n<li>TT TTS TTRS 8J 8S FV<\/li>\n<li>Q2 SQ2 GA<\/li>\n<li>Q3 8U 8U1<\/li>\n<\/ul>\n<h3>Volkswagen<\/h3>\n<ul>\n<li>Beetle 2<\/li>\n<li>EOS<\/li>\n<li>Golf 5 6 7 8 in all versions<\/li>\n<li>ID.3<\/li>\n<li>ID.4<\/li>\n<li>Jetta 1KM 16 16H<\/li>\n<li>Passat B6 B7 B8 B9<\/li>\n<li>Phaeton 3D<\/li>\n<li>Tiguan 5N1<\/li>\n<li>Touran 1T<\/li>\n<li>T-ROC A1<\/li>\n<\/ul>\n<h3>Mercedes Benz<\/h3>\n<ul>\n<li>A-Class W169 W176 W177<\/li>\n<li>B Class W245 W246 W247<\/li>\n<li>C-Class W204 W205 all body styles<\/li>\n<li>CLA Class C117 C118<\/li>\n<li>E-Class W212 W213 all body styles<\/li>\n<li>CL Class C215<\/li>\n<li>EQA250 F2B<\/li>\n<li>GLA 245G F2B<\/li>\n<li>GLB F2B<\/li>\n<li>GLK X204<\/li>\n<li>S-Class W220<\/li>\n<li>Seat<\/li>\n<li>Ateca 5FP also Cupra<\/li>\n<li>Leon 1P 5F KL also Cupra<\/li>\n<li>Karoq NU<\/li>\n<\/ul>\n<h3>Skoda<\/h3>\n<ul>\n<li>Octavia 1Z 5E NX<\/li>\n<li>Superb 2 3 4 3T<\/li>\n<li>Yeti 5L<\/li>\n<\/ul>\n<h3>BMW<\/h3>\n<ul>\n<li>1 Series F40<\/li>\n<li>2 Series F44 F45 F46<\/li>\n<li>X1 F48 U06<\/li>\n<li>X2 F39 U10<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Ein Satz (4 St\u00fcck) hochwertige Marken-Alufelgen, Modell KT15, in der Gr\u00f6\u00dfe 8,5&#215;19 Zoll, Lochkreis 112 mit 5 Loch. Professionell gepr\u00fcft und versandfertig verpackt.<\/p>","protected":false},"featured_media":102918,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1528,1086,1253],"product_tag":[],"class_list":{"0":"post-102184","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-19-zoll-vw","7":"product_cat-felgen","8":"product_cat-vw","9":"product_shipping_class-felge","10":"pa_anzahl-der-einheiten-1484","11":"pa_einpresstiefe-et-1508","12":"pa_fahrzeugmarke-vw","13":"pa_farbe-schwarz","14":"pa_felgenaufbau-einteilig-gegossen","15":"pa_felgenbreite-8-5","16":"pa_felgendesign-konkave-felge","17":"pa_felgenfarbe-schwarz","18":"pa_felgenmaterial-aluminium","19":"pa_felgenmodell-kt15","20":"pa_hersteller-keskin","21":"pa_herstellergarantie-2-jahre","22":"pa_herstellernummer-kt158519511245blp","23":"pa_herstellungsland-und-regi-deutschland","24":"pa_lochkreis-1439","25":"pa_lochzahl-1447","26":"pa_maximale-traglast-720-kg","27":"pa_mit-deckel-ja-nein-ja-von-koenigsraeder","28":"pa_mittenlochbohrung-666-mm","29":"pa_modell-kt15","30":"pa_produktart-kreuzspeiche","31":"pa_zollgroesse-1448","33":"first","34":"instock","35":"taxable","36":"shipping-taxable","37":"purchasable","38":"product-type-simple"},"yoast_head":"<title>19 Zoll Felgen KT15 schwarz f\u00fcr VW Golf 6 7 8 GTI GTD GTE 7R 8R Passat B6 B7 B8 g\u00fcnstig kaufen - Felgenforum<\/title>\n<meta name=\"description\" content=\"Werten Sie Ihren VW Golf mit schwarzen 19 Zoll Felgen KT15 auf. Sportliches Design trifft h\u00f6chste Qualit\u00e4t f\u00fcr Ihren Passat oder GTI. Jetzt entdecken!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/felgenforum.shop\/en\/product\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"19 Zoll Felgen KT15 schwarz f\u00fcr VW Golf 6 7 8 GTI GTD GTE 7R 8R Passat B6 B7 B8 g\u00fcnstig kaufen - Felgenforum\" \/>\n<meta property=\"og:description\" content=\"Werten Sie Ihren VW Golf mit schwarzen 19 Zoll Felgen KT15 auf. Sportliches Design trifft h\u00f6chste Qualit\u00e4t f\u00fcr Ihren Passat oder GTI. Jetzt entdecken!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/felgenforum.shop\/en\/product\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8\/\" \/>\n<meta property=\"og:site_name\" content=\"Felgenforum\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-25T13:14:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8-featured-1000px.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8\\\/\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8\\\/\",\"name\":\"19 Zoll Felgen KT15 schwarz f\u00fcr VW Golf 6 7 8 GTI GTD GTE 7R 8R Passat B6 B7 B8 g\u00fcnstig kaufen - Felgenforum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8-featured-1000px.webp\",\"datePublished\":\"2025-09-22T16:18:56+00:00\",\"dateModified\":\"2026-04-25T13:14:23+00:00\",\"description\":\"Werten Sie Ihren VW Golf mit schwarzen 19 Zoll Felgen KT15 auf. Sportliches Design trifft h\u00f6chste Qualit\u00e4t f\u00fcr Ihren Passat oder GTI. Jetzt entdecken!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8\\\/#primaryimage\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8-featured-1000px.webp\",\"contentUrl\":\"https:\\\/\\\/felgenforum.shop\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8-featured-1000px.webp\",\"width\":1000,\"height\":1000,\"caption\":\"Schwarze 19 Zoll Felgen KT15 passend f\u00fcr VW Golf GTI Modelle\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/produkt\\\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/felgenforum.shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/felgenforum.shop\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"19 Zoll Felgen KT15 schwarz f\u00fcr VW Golf 6 7 8 GTI GTD GTE 7R 8R Passat B6 B7 B8\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/felgenforum.shop\\\/#website\",\"url\":\"https:\\\/\\\/felgenforum.shop\\\/\",\"name\":\"Felgenforum\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/felgenforum.shop\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>","yoast_head_json":{"title":"19 Zoll Felgen KT15 schwarz f\u00fcr VW Golf 6 7 8 GTI GTD GTE 7R 8R Passat B6 B7 B8 g\u00fcnstig kaufen - Felgenforum","description":"Werten Sie Ihren VW Golf mit schwarzen 19 Zoll Felgen KT15 auf. Sportliches Design trifft h\u00f6chste Qualit\u00e4t f\u00fcr Ihren Passat oder GTI. Jetzt entdecken!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/felgenforum.shop\/en\/product\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8\/","og_locale":"en_GB","og_type":"article","og_title":"19 Zoll Felgen KT15 schwarz f\u00fcr VW Golf 6 7 8 GTI GTD GTE 7R 8R Passat B6 B7 B8 g\u00fcnstig kaufen - Felgenforum","og_description":"Werten Sie Ihren VW Golf mit schwarzen 19 Zoll Felgen KT15 auf. Sportliches Design trifft h\u00f6chste Qualit\u00e4t f\u00fcr Ihren Passat oder GTI. Jetzt entdecken!","og_url":"https:\/\/felgenforum.shop\/en\/product\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8\/","og_site_name":"Felgenforum","article_modified_time":"2026-04-25T13:14:23+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8-featured-1000px.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8\/","url":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8\/","name":"19 Zoll Felgen KT15 schwarz f\u00fcr VW Golf 6 7 8 GTI GTD GTE 7R 8R Passat B6 B7 B8 g\u00fcnstig kaufen - Felgenforum","isPartOf":{"@id":"https:\/\/felgenforum.shop\/#website"},"primaryImageOfPage":{"@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8\/#primaryimage"},"image":{"@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8\/#primaryimage"},"thumbnailUrl":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8-featured-1000px.webp","datePublished":"2025-09-22T16:18:56+00:00","dateModified":"2026-04-25T13:14:23+00:00","description":"Werten Sie Ihren VW Golf mit schwarzen 19 Zoll Felgen KT15 auf. Sportliches Design trifft h\u00f6chste Qualit\u00e4t f\u00fcr Ihren Passat oder GTI. Jetzt entdecken!","breadcrumb":{"@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8\/#primaryimage","url":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8-featured-1000px.webp","contentUrl":"https:\/\/felgenforum.shop\/wp-content\/uploads\/2025\/09\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8-featured-1000px.webp","width":1000,"height":1000,"caption":"Schwarze 19 Zoll Felgen KT15 passend f\u00fcr VW Golf GTI Modelle"},{"@type":"BreadcrumbList","@id":"https:\/\/felgenforum.shop\/produkt\/19-zoll-felgen-kt15-schwarz-fuer-vw-golf-6-7-8-gti-gtd-gte-7r-8r-passat-b6-b7-b8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/felgenforum.shop\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/felgenforum.shop\/shop\/"},{"@type":"ListItem","position":3,"name":"19 Zoll Felgen KT15 schwarz f\u00fcr VW Golf 6 7 8 GTI GTD GTE 7R 8R Passat B6 B7 B8"}]},{"@type":"WebSite","@id":"https:\/\/felgenforum.shop\/#website","url":"https:\/\/felgenforum.shop\/","name":"Rim forum","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/felgenforum.shop\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product\/102184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/comments?post=102184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/media\/102918"}],"wp:attachment":[{"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/media?parent=102184"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_brand?post=102184"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_cat?post=102184"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/felgenforum.shop\/en\/wp-json\/wp\/v2\/product_tag?post=102184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}